{"id":102273,"date":"2018-12-04T10:34:56","date_gmt":"2018-12-04T16:34:56","guid":{"rendered":"http:\/\/sintesis.com.mx\/hidalgo\/?p=102273"},"modified":"2018-12-04T10:34:56","modified_gmt":"2018-12-04T16:34:56","slug":"festival-globo-bush-stone-temple-pilots-vl019","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/hidalgo\/2018\/12\/04\/festival-globo-bush-stone-temple-pilots-vl019\/","title":{"rendered":"Festival Nacional del Globo \/ Bush &#038; Stone Temple Pilots \/ VL019"},"content":{"rendered":"<p><strong>I.-<\/strong> Todo est\u00e1 listo para efectuarse el pr\u00f3ximo 08 de Diciembre en la que se estar\u00e1 llevando en el Estado de M\u00e9xico, la Celebraci\u00f3n de la 2\u00aa. Edici\u00f3n Festival Nacional del Globo en San Juan Teotihuac\u00e1n (2018); donde se vivir\u00e1 de cerca la magia de los 4 elementos, a un costado de las monumentales pir\u00e1mides y que constara de m\u00fasica, gastronom\u00eda anexo a m\u00faltiples actividades como globos aerost\u00e1ticos.<\/p>\n<p>a). Durante todo el d\u00eda en plenas \u00e1reas del Rancho El H\u00f3rreo, el presente podr\u00e1 recrearse auditivamente los sentidos con la m\u00fasica diversa de: Chairel, Julieta Soto, Dani Rude Boy, Jet Jaguar, Tasha, Dj Perro, Love La Femme, Motor, Mir\u00f3, Alejandro Marcovich, y El Tri celebrando su 50 aniversario.<\/p>\n<p>b). La conmemoraci\u00f3n ser\u00e1 parte tambi\u00e9n como atractivo del R\u00e9cord Guiness al tapete floral m\u00e1s grande del mundo realizado por Jardines de M\u00e9xico, con una extensi\u00f3n de 1.6 hect\u00e1reas, cerca de 150 mil Nochebuenas.<\/p>\n<p><strong>II.- <\/strong>La amplia vereda recorrida en el ocaso de este 2018 ha sido determinante para San Pascualito Rey, con 18 a\u00f1os de su fundaci\u00f3n quienes por cierto reeditaron en vinil el: Sufro, Sufro, Sufro. Tambi\u00e9n dieron a conocer el tema m\u00e1s pesado de su historia: Lo Que Quieres Ver (Todo Nos Trajo Hasta Hoy, 2017).<\/p>\n<p>Del mismo modo ha llegado el punto final a una importante etapa de su trayectoria para este 05 de Diciembre en el Lunario del Auditorio Nacional (Ciudad de M\u00e9xico), con la que recorrer\u00e1n parte de su discograf\u00eda y volver\u00e1n a interpretar temas que hace tiempo no se escuchan en vivo a\u00f1adi\u00e9ndole elementos de Teatro Kabuki exclusivo para este show. Los encargados de la apertura corresponder\u00e1 a: The Chamanas.<\/p>\n<p>Con esta presentaci\u00f3n Alex Otaola se despide de la banda para seguir adelante con nuevos proyectos como cada uno de los m\u00fasicos que ha compartido escenario y estudios con San Pascualito Rey.<\/p>\n<p><strong>III.-<\/strong> La conexi\u00f3n que llevo a Bush y Stone Temple Pilots en nuestro pa\u00eds con antecedente interesante en el pasado Force Fest 2018, definitivamente dos de las bandas m\u00e1s importantes en la escena del grunge y rock de finales de los noventas, quienes recorrer\u00e1n juntos algunos sitios geogr\u00e1ficos latinoamericanos con la ponderada gira Revoluci\u00f3n Tour 2019.<\/p>\n<p>Esta vez las dos formaciones inglesa y estadounidense respectivamente regresan a nuestro pa\u00eds teniendo fecha en el Front\u00f3n M\u00e9xico (CdMx) \u00a0el 24 de Febrero a las 20 horas. Los boletos estar\u00e1n disponibles a partir del 05 de diciembre por el sistema de Stubhub.<\/p>\n<p><strong>IV.-<\/strong> Para la ciudad industrial de Ciudad Sahag\u00fan, una de las festividades m\u00e1s destacadas de fin de a\u00f1o, la que conocemos hoy como Festival Globos de Cantolla Hidalgo que en este 2018 coinciden con los 66 a\u00f1os de asentamiento de la localidad, actividad que festejara su onceava aventura.<\/p>\n<p>La celebraci\u00f3n consta de construir y elevar globos de papel, aunado a la reuni\u00f3n de personas afines a la misma y se destaca como una tradici\u00f3n joven en uni\u00f3n recreativa sana. La actividad oficialmente se efectuara en el Estadio de Beisbol (IMSS) este s\u00e1bado 08 de Diciembre, a partir de las 11 hasta las 23 horas. Gratuito, con previo desfile proyectado de las 18 a 20:30 horas, por las principales calles de la ciudad obrera cosmopolita de luces enclavada en el estado de Hidalgo para todo el mundo.<\/p>\n<p>El mismo evento arrancara con diferentes tipos de actividades, entre las que incluyen los caracter\u00edsticos talleres de globos que se impartir\u00e1n ah\u00ed mismos (promoviendo a su vez al no consumo de los artefactos con manufactura china), expo alebrijes, variedades gastron\u00f3micas, artesan\u00edas, bandas de marching bands con un contingente de 600 personas, m\u00fasica (rock &amp; pop); ballet, canto (regional mexicano) y contingente de motocicletas; que juntos har\u00e1n brillar sin excepci\u00f3n a la suma de voluntades, elevando ilusiones, creando tradiciones.<\/p>\n<p><strong>V.-<\/strong> Tras anunciar Vive Latino formalmente su pr\u00f3xima y vig\u00e9sima edici\u00f3n misma que se celebrara para el pr\u00f3ximo a\u00f1o del 2019, para el mes de marzo, en locaci\u00f3n familiar como lo es el Foro Sol de la capital mexicana. Para esta ocasi\u00f3n oficialmente OCESA da a conocer la distribuci\u00f3n del cartel quedando de la siguiente manera:<\/p>\n<p>Marzo 16: Caifanes, Daniela Spalla, Divisi\u00f3n Min\u00fascula, Ferm\u00edn IV, Galindo, Bomba Est\u00e9reo, Fantastic Negrito, Gandhi, Hello Seahorse!, Editors, Guasones, Juanse, Jumbo, Foals, Kill Aniston, Liquits, Lanza Internacional, Maching\u00f3n, Los Afro Brothers, Fobia, LP, Mad Tree, Mateo Kingman, Miranda!, Intocable, Noah Pino Palo, Oi-Skall Mates, Rude Boys, Nach, Ska-P, Siddhartha, Technotronic, Sonido Gallo Negro, Viva Suecia, Too Many Zooz, Ximena Sari\u00f1ana, Santa Sabina XXX y Zona Ganjah.<\/p>\n<p>Marzo 17: The 1975, Alem\u00e1n, Alfonso Andr\u00e9 &amp; Amigos (Homenaje a David Bowie), Bengala, Correos, Draco Rosa, El Gran Silencio, Bunbury, Flor de Toloache, Caf\u00e9 Tacvba, Haelos, Ilegales, Javier B\u00e1tiz, La Casta\u00f1eda, La Orquesta Mondrag\u00f3n, La Pingo Orquesta, Dillon Francis, La Sexta Vocal, El Tri, Los Viejos, Los Estramb\u00f3ticos, Odisseo, Rastrillos, La Orquesta de P\u00e9rez Prado, Miguel Mateos, Juanes, Rawayana, Korn, Skip &amp; Die, Stoner Love, Turf, The Bomboras, The Inspector Cluzo, Los Tres, The Plastics Revolution, Tino El Ping\u00fcino, Santana, Snow Patrol y Vaquero Negro.<\/p>\n<p><strong>\u00a0<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>Twitter<\/strong>: <a href=\"http:\/\/twitter.com\/ARNULFOVAZQUEZ\">@ARNULFOVAZQUEZ<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segunda Edici\u00f3n Festival Nacional del Globo \/ Bush y Stone Temple Pilots en nuestro pa\u00eds \/ Vive Latino 2019<\/p>\n","protected":false},"author":7,"featured_media":102274,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[3197,22,38447,3004,29819],"yst_prominent_words":[38439,38440,5345,5031,8004,6718,4855,4910,5614,5293,8702,38445,38442,38446,5131,38443,38438,38444,38441,5126],"class_list":["post-102273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vox","tag-globo","tag-hidalgo","tag-stone-temple-pilots","tag-vive-latino","tag-vox"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/102273"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/comments?post=102273"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/102273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/media\/102274"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/media?parent=102273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/categories?post=102273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/tags?post=102273"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/yst_prominent_words?post=102273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}