{"id":167675,"date":"2021-09-26T12:11:06","date_gmt":"2021-09-26T17:11:06","guid":{"rendered":"https:\/\/sintesis.com.mx\/hidalgo\/?p=167675"},"modified":"2021-09-26T12:11:06","modified_gmt":"2021-09-26T17:11:06","slug":"nunca-termina-construir","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/hidalgo\/2021\/09\/26\/nunca-termina-construir\/","title":{"rendered":"Nunca se termina de construir la agenda legislativa: H\u00e9ctor Ch\u00e1vez Ruiz"},"content":{"rendered":"<p>Debido a que siempre hay <strong>diferentes necesidades, propuestas, demandas y peticiones por parte de la poblaci\u00f3n<\/strong>, es muy dif\u00edcil <strong>terminar se construir una agenda legislativa<\/strong>, asegur\u00f3 el <strong>diputado federal por <a href=\"https:\/\/sintesis.com.mx\/hidalgo\/2021\/05\/15\/maestros-botin-politico\/\">Hidalgo<\/a>, <a href=\"https:\/\/twitter.com\/hctorchvezruiz2?lang=es\">H\u00e9ctor Ch\u00e1vez Ruiz<\/a><\/strong>.<\/p>\n<p>Lugo de asegurar que durante campa\u00f1a, se llevan y presentan ya una serie de propuestas, y al mismo tiempo se reciben muchas inquietudes de la ciudadan\u00eda, el legislador federal asegur\u00f3 que es de esa manera en que se construye la agenda a seguir para que en la medida de lo posible se pueda dar respuesta a las demandas de la ciudadan\u00eda:<\/p>\n<p>\u201cSin embargo, una agenda legislativa nunca se termina de conformar, porque todos los d\u00edas surge una necesidad, de los compa\u00f1eros, de la gente o de un grupo y eso es lo que nos va retroalimentando para poder llevar a tribuna lo que se considera que es prioritario y que de alguna manera puede dar resultados en beneficio de la poblaci\u00f3n en general\u201d.<\/p>\n<p>Ch\u00e1vez Ruiz, a\u00f1adi\u00f3 que en los 15 d\u00edas que apenas llevan en el Congreso de la Uni\u00f3n, ya tienen listos varios temas a presentar en tribuna entre ellos el del combate a la corrupci\u00f3n, as\u00ed como para enfrentar situaciones de emergencia como la que se vive en estos momentos en diferentes regiones del estado, pero principalmente en la zona de Tula, para que se alguna manera ya no se repitan situaciones de este tipo y mucho menos decesos.<\/p>\n<p>\u201cEn este caso se tendr\u00e1n que presentar los puntos de acuerdo necesarios para encontrar una soluci\u00f3n que sea definitiva al problema de las inundaciones no solamente en la regi\u00f3n de Tula, sino en todos los lugares donde es recurrente que se presente este tipo de problemas a cada temporada de lluvias\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a que siempre hay diferentes necesidades, propuestas, demandas y peticiones por parte de la poblaci\u00f3n, es muy dif\u00edcil terminar se construir una agenda legislativa, asegur\u00f3 el diputado federal por Hidalgo, H\u00e9ctor Ch\u00e1vez Ruiz. Lugo de asegurar que durante campa\u00f1a, se llevan y presentan ya una serie de propuestas, y al mismo tiempo se reciben [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,86462],"tags":[931,88789,28479,22,88790,88787,702,1215,3773,88788],"yst_prominent_words":[6657,6846,5241,7817,9232,5464,7293,5635,5054,6847,4979,5101,5572,9351,7786,5091,5621,5037],"class_list":["post-167675","post","type-post","status-publish","format-standard","hentry","category-metropoli-hidalgo","category-politica","tag-agenda","tag-construir","tag-hector-chavez-ruiz","tag-hidalgo","tag-legislativa","tag-nunca","tag-politica","tag-slide","tag-slideapp","tag-termina"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/167675"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/comments?post=167675"}],"version-history":[{"count":2,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/167675\/revisions"}],"predecessor-version":[{"id":167681,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/167675\/revisions\/167681"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/media?parent=167675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/categories?post=167675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/tags?post=167675"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/yst_prominent_words?post=167675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}