{"id":178801,"date":"2022-02-15T15:04:06","date_gmt":"2022-02-15T21:04:06","guid":{"rendered":"https:\/\/sintesis.com.mx\/hidalgo\/?p=178801"},"modified":"2022-02-15T15:04:06","modified_gmt":"2022-02-15T21:04:06","slug":"exhortan-a-cuidar-datos-personales-de-ninas-ninos-y-adolescentes","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/hidalgo\/2022\/02\/15\/exhortan-a-cuidar-datos-personales-de-ninas-ninos-y-adolescentes\/","title":{"rendered":"Exhortan a cuidar datos personales de ni\u00f1as, ni\u00f1os y adolescentes"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><strong>El Poder Ejecutivo de Hidalgo, hizo un llamado a los medios de comunicaci\u00f3n, para proteger los datos personales de Ni\u00f1as, Ni\u00f1os y Adolescentes (NNA),<\/strong> al momento de difundir informaci\u00f3n en donde alg\u00fan menor de edad se vea implicado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A trav\u00e9s de la Coordinaci\u00f3n General de Comunicaci\u00f3n Gubernamental, se exhort\u00f3 a quienes forman parte de los medios, a cumplir con el marco normativo en materia de protecci\u00f3n del derecho a la intimidad y protecci\u00f3n de datos personales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En ese sentido, record\u00f3 que la Ley General de los Derechos de las Ni\u00f1as, Ni\u00f1os y Adolescentes estableci\u00f3 en el art\u00edculo 79 que <strong>\u201clas autoridades, federales, estatales y municipales, en el \u00e1mbito de sus respectivas competencias, garantizar\u00e1n la protecci\u00f3n de la identidad e intimidad de ni\u00f1as, ni\u00f1os y adolescentes que sean v\u00edctimas, ofendidos, testigos o que est\u00e9n relacionados de cualquier manera en la comisi\u00f3n de un delito, a fin de evitar su identificaci\u00f3n p\u00fablica. La misma protecci\u00f3n se otorgar\u00e1 a adolescentes a quienes se les atribuya la realizaci\u00f3n o participaci\u00f3n en un delito, conforme a la legislaci\u00f3n aplicable en la materia\u201d.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lo anterior, derivado de los hechos recientes, en los que se difundieron informaci\u00f3n y datos personales de un menor de edad involucrado supuestamente en una adopci\u00f3n temporal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u201cLo anterior se hace de su conocimiento, y se solicita su observancia, como medida para evitar la repetici\u00f3n de actos violatorios de derechos humanos\u201d<\/strong><em>,<\/em> se ley\u00f3 en la circular dispersada a los diferentes medios de comunicaci\u00f3n en la entidad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, la Coordinaci\u00f3n de Comunicaci\u00f3n Gubernamental, refiri\u00f3 que en el caso de que un agente estatal o alguna persona divulguen, compartan, distribuyan, comercialicen y\/o publiquen im\u00e1genes, audios o videos en donde aparezcan NNA, sin que exista justificaci\u00f3n legal para ello, se considera una vulneraci\u00f3n al derecho a la intimidad.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Poder Ejecutivo de Hidalgo, hizo un llamado a los medios de comunicaci\u00f3n, para proteger los datos personales de Ni\u00f1as, Ni\u00f1os y Adolescentes (NNA), al momento de difundir informaci\u00f3n en donde alg\u00fan menor de edad se vea implicado. A trav\u00e9s de la Coordinaci\u00f3n General de Comunicaci\u00f3n Gubernamental, se exhort\u00f3 a quienes forman parte de los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[747,22,27,40771,23,2109,631,90435,1215,3773,32433],"yst_prominent_words":[5835,9732,9801,19520,5710,7726,21637,7681,9646,5836,8157,8153,5837,8155,10564,4923],"class_list":["post-178801","post","type-post","status-publish","format-standard","hentry","category-metropoli-hidalgo","tag-adolescentes","tag-hidalgo","tag-hidesnoticia","tag-hidesnoticiaapp","tag-hidslide","tag-ninas","tag-ninos","tag-proteccion-de-datos-personales","tag-slide","tag-slideapp","tag-slider"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/178801"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/comments?post=178801"}],"version-history":[{"count":3,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/178801\/revisions"}],"predecessor-version":[{"id":178810,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/178801\/revisions\/178810"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/media?parent=178801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/categories?post=178801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/tags?post=178801"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/yst_prominent_words?post=178801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}