{"id":188043,"date":"2022-06-21T17:45:35","date_gmt":"2022-06-21T22:45:35","guid":{"rendered":"https:\/\/sintesis.com.mx\/hidalgo\/?p=188043"},"modified":"2022-06-21T17:45:35","modified_gmt":"2022-06-21T22:45:35","slug":"capacita-ihm-a-municipios-en-perspectiva-de-genero","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/hidalgo\/2022\/06\/21\/capacita-ihm-a-municipios-en-perspectiva-de-genero\/","title":{"rendered":"Capacita IHM a municipios en perspectiva de g\u00e9nero"},"content":{"rendered":"<p>El <strong>Instituto Hidalguense de las Mujeres (IHM),<\/strong> lleva a cabo, desde abril y hasta agosto, un programa de capacitaci\u00f3n en materia de g\u00e9nero, para funcionariado municipal, con \u00e9nfasis en las titulares de las<strong> Instancias Municipales para el Desarrollo de las Mujeres (IMDM)<\/strong>, a fin de que cuenten con herramientas para aplicar la perspectiva de g\u00e9nero en sus pol\u00edticas y acciones de gobierno.<\/p>\n<p>La directora general del IHM,<strong> Mar\u00eda Concepci\u00f3n Hern\u00e1ndez Arag\u00f3n<\/strong>, destac\u00f3 dos proyectos, como el<strong> \u201cPrograma Integral de Capacitaci\u00f3n con Perspectiva de G\u00e9nero para la Igualdad entre Mujeres y Hombres\u201d,<\/strong> dirigido a servidoras y servidores p\u00fablicos de la administraci\u00f3n p\u00fablica municipal que se desempe\u00f1an en \u00e1reas directivas, planeaci\u00f3n, recursos humanos, as\u00ed como quienes ejecutan acciones en materia de g\u00e9nero, igualdad entre mujeres y hombres y prevenci\u00f3n de la violencia contra las mujeres. En el curso participan los municipios de todas las regiones del estado, organizados en cinco grupos.<\/p>\n<p>El proceso de formaci\u00f3n obedece a la obligatoriedad legal y moral que tienen todas las y los servidores p\u00fablicos de los tres niveles de gobierno, de atender las necesidades de las mujeres, independientemente del \u00e1rea en que se desenvuelvan.<strong> \u201cEste tema no compete s\u00f3lo a las instancias de atenci\u00f3n a mujeres, sino a todo el funcionariado, incluyendo a la Asamblea Municipal\u201d<\/strong>, dijo Concepci\u00f3n Hern\u00e1ndez, para dejar claro que la funci\u00f3n de la IMDM es coordinar, pero la responsabilidad es del ayuntamiento en su conjunto.<\/p>\n<p>El segundo proyecto es el de Capacitaci\u00f3n a titulares de las <strong>Instancias Municipales de las Mujeres de Nuevo Ingreso de la administraci\u00f3n 2020-2024,<\/strong> para darles herramientas que les permitan incluir en sus programas de trabajo el enfoque de derechos humanos, perspectiva de g\u00e9nero e interseccionalidad.<\/p>\n<p><strong>En esta capacitaci\u00f3n se abordaron los temas:<\/strong> Funciones y atribuciones de las titulares de las Instancias; contenidos b\u00e1sicos para la igualdad; marco normativo de los derechos humanos de las mujeres; construcci\u00f3n de la masculinidad; causas y consecuencias de la violencia contra las mujeres (acoso y hostigamiento sexual); Protocolo de Atenci\u00f3n Especializada del IHM; Medidas y \u00f3rdenes de Protecci\u00f3n; Funciones del o la conciliadora municipal en la atenci\u00f3n de la violencia contra las mujeres; Sistema Municipal para Prevenir, Atender, Sancionar y Erradicar la Violencia contra las Mujeres; Transversalidad de la Perspectiva de G\u00e9nero; Lenguaje incluyente y sin discriminaci\u00f3n; y seguimiento a los programas de trabajo de la Instancias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Hidalguense de las Mujeres (IHM), lleva a cabo, desde abril y hasta agosto, un programa de capacitaci\u00f3n en materia de g\u00e9nero, para funcionariado municipal, con \u00e9nfasis en las titulares de las Instancias Municipales para el Desarrollo de las Mujeres (IMDM), a fin de que cuenten con herramientas para aplicar la perspectiva de g\u00e9nero [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[89949,86628,22,88082,84344,23,89177,33877,1215,32433],"yst_prominent_words":[5197,35428,5026,7748,21151,21150,30343,10343,50444,40095,7141,4838,27783,7738,5023,76072,5153,26819],"class_list":["post-188043","post","type-post","status-publish","format-standard","hentry","category-metropoli-hidalgo","tag-frida-morales","tag-hdhoyesnoticia","tag-hidalgo","tag-hidalgo-hoyesnoticia","tag-hideesnoticia","tag-hidslide","tag-instituto-hidalguense-de-las-mujeres-ihm","tag-maria-concepcion-hernandez-aragon","tag-slide","tag-slider"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/188043"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/comments?post=188043"}],"version-history":[{"count":3,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/188043\/revisions"}],"predecessor-version":[{"id":188050,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/188043\/revisions\/188050"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/media?parent=188043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/categories?post=188043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/tags?post=188043"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/yst_prominent_words?post=188043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}