{"id":216781,"date":"2023-06-16T21:08:13","date_gmt":"2023-06-17T03:08:13","guid":{"rendered":"https:\/\/sintesis.com.mx\/hidalgo\/?p=216781"},"modified":"2023-06-16T21:08:13","modified_gmt":"2023-06-17T03:08:13","slug":"utvam-10","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/hidalgo\/2023\/06\/16\/utvam-10\/","title":{"rendered":"UTVAM"},"content":{"rendered":"<p>Por:<\/p>\n<p><strong>Abril Hern\u00e1ndez Guerrero*<\/strong><br \/>\n<strong>Dra. J. Patricia Mu\u00f1oz Ch\u00e1vez**<\/strong><\/p>\n<p>En la actualidad existen diversos trastornos que influyen en el desarrollo social y emocional de las personas que los padecen. Uno de ellos es el Trastorno de D\u00e9ficit de Atenci\u00f3n con Hiperactividad (TDAH), el cual se ha determinado que se trata de una dismorfolog\u00eda, disfunci\u00f3n y baja conectividad de redes neuronales del cerebro que afecta la parte cognitiva, como la inhibici\u00f3n, falta de atenci\u00f3n y percepci\u00f3n del tiempo. Adem\u00e1s, retrasa la madurez cerebral e incluso esta puede no llegar a completarse.<\/p>\n<p>A menudo, el TDHA se asocia con ni\u00f1os, adolescentes y j\u00f3venes debido a las conductas biol\u00f3gicas naturales que el cuerpo humano experimenta durante esas etapas. Sin embargo, el National Comorbility Survey Replication estima que m\u00e1s del 4 por ciento de la poblaci\u00f3n adulta cumple con los criterios para el D\u00e9ficit de Atenci\u00f3n.<\/p>\n<p>En la actualidad, debido a la carga emocional que represent\u00f3 la pandemia, para muchas empresas es casi un requisito trabajar bajo presi\u00f3n y actuar de manera r\u00e1pida y eficiente. Sin embargo, para las personas con TDAH esta din\u00e1mica de trabajo y complejidad organizacional en muchos casos les dificulta la permanencia en sus puestos de trabajo.<\/p>\n<p>Las organizaciones establecen lineamientos, pol\u00edticas y est\u00e1ndares que deben cumplirse, pero, que para las personas con TDAH son dif\u00edciles de seguir al pie de la letra. Por ejemplo, cumplir con el horario de trabajo, prestar atenci\u00f3n a las instrucciones y controlar las emociones. Al respecto, en las \u00faltimas d\u00e9cadas han surgido propuestas en el entorno de trabajo que coadyuven a la mejora de la calidad de vida del trabajador con este trastorno, tal es el caso de Cornel University en el 2001 y Adamou en el 2013 que sugirieron hacer ciertos cambios en el lugar de trabajo, como uso de aud\u00edfonos, disminuir los factores de distracci\u00f3n, brindar una oficina privada, asignar un supervisor que los monitoree constantemente y ayudarlos a fijar metas alcanzables a corto plazo.<\/p>\n<p>A pesar de estas propuestas, a menudo el mundo laboral no es emp\u00e1tico con las personas que sufren este tipo de trastornos, ya que buscan ser lo m\u00e1s eficientes posible. No obstante, existen opciones de trabajo de forma independiente para los adultos con TDAH, ya que son muy creativos. Algunas opciones son escritor, dise\u00f1ador gr\u00e1fico y fot\u00f3grafo, en los cuales se puede trabajar por cuenta propia y les permita desarrollar al m\u00e1ximo su potencial creativo.<\/p>\n<p>Finalmente, es evidente que, a pesar de los avances logrados en la inclusi\u00f3n de sectores vulnerables en nuestra sociedad, las personas con TDAH todav\u00eda se enfrentan a barreras laborales significativas. Es crucial que los tomadores de decisiones y los responsables de formular pol\u00edticas p\u00fablicas tomen conciencia de esta realidad y promuevan la inclusi\u00f3n de las personas con TDAH. Solo a trav\u00e9s de un enfoque inclusivo y emp\u00e1tico podremos garantizar que todos los individuos tengan igualdad de oportunidades para desarrollar su potencial y contribuir de manera significativa a la fuerza laboral.<\/p>\n<p><em><strong>*Estudiante de Desarrollo de Negocios de la UTVAM <\/strong><\/em><br \/>\n<em><strong>**Investigadora de la UTVAM<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Abril Hern\u00e1ndez Guerrero* Dra. J. Patricia Mu\u00f1oz Ch\u00e1vez** En la actualidad existen diversos trastornos que influyen en el desarrollo social y emocional de las personas que los padecen. Uno de ellos es el Trastorno de D\u00e9ficit de Atenci\u00f3n con Hiperactividad (TDAH), el cual se ha determinado que se trata de una dismorfolog\u00eda, disfunci\u00f3n y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":171724,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[29819],"yst_prominent_words":[18123,5544,62826,34146,5479,5434,10421,4879,8513,15927,5929,5147,5572,6561,5151,12171,11531],"class_list":["post-216781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vox","tag-vox"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/216781"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/comments?post=216781"}],"version-history":[{"count":1,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/216781\/revisions"}],"predecessor-version":[{"id":216782,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/216781\/revisions\/216782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/media\/171724"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/media?parent=216781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/categories?post=216781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/tags?post=216781"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/yst_prominent_words?post=216781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}