{"id":269965,"date":"2025-04-18T14:16:06","date_gmt":"2025-04-18T20:16:06","guid":{"rendered":"https:\/\/sintesis.com.mx\/hidalgo\/?p=269965"},"modified":"2025-04-18T14:16:06","modified_gmt":"2025-04-18T20:16:06","slug":"supervisan-que-transporte-publico","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/hidalgo\/2025\/04\/18\/supervisan-que-transporte-publico\/","title":{"rendered":"Supervisan que transporte p\u00fablico preste servicio adecuado en Semana Santa"},"content":{"rendered":"<p>Del 14 al 20 de abril, el personal adscrito a la Direcci\u00f3n de Supervisi\u00f3n y Vigilancia del Sistema de Transporte Convencional de Hidalgo (STCH), organismo sectorizado a la Secretar\u00eda de Movilidad y Transporte, refuerza sus actividades en diferentes municipios del estado, sobre todo en aquellos en donde el tr\u00e1nsito de turistas incrementa en esta temporada vacacional.<\/p>\n<p>Se trata de verificar la adecuada prestaci\u00f3n del servicio, el cobro de tarifas, cumplimiento del itinerario establecido, as\u00ed como la correcta operaci\u00f3n de las unidades de transporte p\u00fablico por las personas operadoras.<\/p>\n<p>El personal a cargo de las tareas est\u00e1 debidamente identificado a trav\u00e9s de las credenciales y elementos del uniforme institucional correspondientes.<\/p>\n<p>Las v\u00edas para iniciar una queja ante posibles irregularidades en el servicio de transporte p\u00fablico:<\/p>\n<p>\u2022 N\u00fameros telef\u00f3nicos: 800 503 2002 \u00f3 771 526 1284 en un horario de 9:00 a 17:00 horas.<\/p>\n<p>\u2022 Direcci\u00f3n de correo electr\u00f3nico: quejatransporte@hidalgo.gob.mx las 24 horas del d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 14 al 20 de abril, el personal adscrito a la Direcci\u00f3n de Supervisi\u00f3n y Vigilancia del Sistema de Transporte Convencional de Hidalgo (STCH), organismo sectorizado a la Secretar\u00eda de Movilidad y Transporte, refuerza sus actividades en diferentes municipios del estado, sobre todo en aquellos en donde el tr\u00e1nsito de turistas incrementa en esta temporada [&hellip;]<\/p>\n","protected":false},"author":134,"featured_media":269967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[95392,22,27,40771,76894,85901,3772,904,32433,80159,234],"yst_prominent_words":[4920,4991,6439,7216,6573,6568],"class_list":["post-269965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metropoli-hidalgo","tag-cifras-semana-santa-2023","tag-hidalgo","tag-hidesnoticia","tag-hidesnoticiaapp","tag-hidhoyesnoticia","tag-hidhoyesnoticiaapp","tag-hoyesnoticiaapp","tag-semana-santa","tag-slider","tag-sliderapp","tag-transporte"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/269965"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/comments?post=269965"}],"version-history":[{"count":2,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/269965\/revisions"}],"predecessor-version":[{"id":269969,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/posts\/269965\/revisions\/269969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/media\/269967"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/media?parent=269965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/categories?post=269965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/tags?post=269965"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/hidalgo\/wp-json\/wp\/v2\/yst_prominent_words?post=269965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}