{"id":140082,"date":"2019-01-14T17:04:30","date_gmt":"2019-01-14T23:04:30","guid":{"rendered":"http:\/\/sintesis.com.mx\/puebla\/?p=140082"},"modified":"2019-01-14T17:04:30","modified_gmt":"2019-01-14T23:04:30","slug":"roban-mas-de-1mdp-a-cuentahabientes-tolin","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2019\/01\/14\/roban-mas-de-1mdp-a-cuentahabientes-tolin\/","title":{"rendered":"Roban m\u00e1s de 1 mdp a cuentahabientes en Plaza Tol\u00edn"},"content":{"rendered":"<p>Presuntos delincuentes llegaron al <strong>estacionamiento de plaza Tol\u00edn<\/strong>, sobre Calzada Zaragoza, para apoderarse de m\u00e1s de un mill\u00f3n de pesos en efectivo que <strong>depositar\u00edan dos cuentahabientes<\/strong> en el banco Santander.<\/p>\n<p>Los primeros reportes indican que poco despu\u00e9s de las 08:30 horas de este lunes, <strong>se solicit\u00f3 auxilio al n\u00famero de emergencia<\/strong> luego de que los tripulantes de una camioneta RAM de color gris reportaron el robo.<\/p>\n<p>Al lugar llegaron elementos de la <strong>Polic\u00eda Municipal<\/strong> para tomar conocimiento del hecho, siendo los agraviados quienes les refirieron que estaban a la espera de que abrieran el banco para realizar <strong>el dep\u00f3sito cuando hombres<\/strong> rompieron el vidrio de la ventanilla y mediante amenazas los obligaron a entregar el efectivo.<\/p>\n<p>Por lo ocurrido tambi\u00e9n tom\u00f3 conocimiento personal de la <strong>Agencia Estatal de Investigaci\u00f3n<\/strong> y se indic\u00f3 a los afectados acudir a presentar su denuncia para <strong>dar con el paradero<\/strong> de los probables responsables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presuntos delincuentes llegaron al estacionamiento de Plaza Tol\u00edn, sobre Calzada Zaragoza, para apoderarse de m\u00e1s de un mill\u00f3n de pesos en efectivo<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1285,3],"tags":[732,27,8254,1286,19457,15631,18,4842],"yst_prominent_words":[],"class_list":["post-140082","post","type-post","status-publish","format-standard","hentry","category-justicia","category-puebla","tag-asalto","tag-hoyesnoticia","tag-hoyesnoticiaapp","tag-justicia","tag-plaza-tolin","tag-presuntos-delincuentes","tag-puebla","tag-robo-a-cuentahabiente"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/140082"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=140082"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/140082\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=140082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=140082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=140082"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=140082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}