{"id":146687,"date":"2019-02-18T18:51:18","date_gmt":"2019-02-19T00:51:18","guid":{"rendered":"http:\/\/sintesis.com.mx\/puebla\/?p=146687"},"modified":"2019-02-18T18:51:45","modified_gmt":"2019-02-19T00:51:45","slug":"ine-acepta-unico-aspirante-independiente","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2019\/02\/18\/ine-acepta-unico-aspirante-independiente\/","title":{"rendered":"INE acepta \u00fanico aspirante a candidato independiente"},"content":{"rendered":"<p>El Instituto Nacional Electoral (INE) entreg\u00f3 la constancia de aspirante a candidato independiente a la gubernatura, a <strong>Juan Alejandro Amoros Herrera<\/strong> quien fue el \u00fanico de los cinco que cubri\u00f3 con los requisitos establecidos en la convocatoria, por lo que apartir del 14 de marzo <strong>deber\u00e1 de recabar el apoyo ciudadano<\/strong> para lograr la candidatura y aparecer en la boleta electoral.<\/p>\n<p>Alejandro Amoros fue representante del<strong> Partido Encuentro Social<\/strong> en el Distrito electoral federal 4, antes cabecera en Zacapoaxtla, y ahora <strong>busca ser el \u00fanico candidato independiente a Casa Puebla<\/strong>, por lo que durante 30 d\u00edas podr\u00e1 realizar actos tendentes a recabar el 1.5 por ciento de las<span class=\"Apple-converted-space\">\u00a0 <\/span>rubricas, que representan <strong>66 mil 776 apoyos de poblanos del Listado Nominal<\/strong> correspondiente <a href=\"https:\/\/twitter.com\/INE_PUEBLA?lang=es\">con corte del 15 de diciembre del 2017<\/a>.<\/p>\n<p>El aspirante a candidato independiente <strong>deber\u00e1 financiarse con recursos privados<\/strong> de origen l\u00edcito y para los actos tendentes a <strong>recabar el apoyo ciudadano<\/strong> estar\u00e1 sujeto al siguiente tope de gastos establecido en <strong>cuatro millones 296 mil 333 pesos<\/strong>.<\/p>\n<p>Cabe mencionar que los recursos privados que obtengan <strong>ser\u00e1n fiscalizados por el \u00f3rgano comicial<\/strong> y en caso lo lograr el n\u00famero de firmas y sea el candidato independiente, el INE le dar\u00e1<strong> financiamiento p\u00fablico<\/strong> para la obtenci\u00f3n del voto durante los 60 d\u00edas de campa\u00f1a que marca el calendario oficial.<\/p>\n<p>A m\u00e1s tardar el 30 de marzo, el Consejo Local del INE en Puebla sesionar\u00e1 <strong>para acordar lo conducente a la solicitud de registro<\/strong> de <a href=\"http:\/\/sintesis.com.mx\/puebla\/?s=independiente\">candidatura independiente<\/a> a la gubernatura de Puebla.<\/p>\n<p>En m\u00e1s informaci\u00f3n, la Junta local del INE dio a conocer que este d\u00eda <strong>se aplicar\u00e1n en 16 sedes en la entidad<\/strong>, los ex\u00e1menes para seleccionar a las y los interesados en trabajar como supervisores o capacitadores asistentes electorales, que <strong>ser\u00e1n quienes notificar\u00e1n, sensibilizar\u00e1n y capacitar\u00e1n a las y los funcionarios<\/strong> de casilla que recibir\u00e1n los votos de sus vecinos el pr\u00f3ximo 2 de junio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Nacional Electoral (INE) entreg\u00f3 la constancia de aspirante a candidato independiente a la gubernatura, a Juan Alejandro Amoros Herrera<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[20735,10314,2077,27,8254,365,20736,5988,18],"yst_prominent_words":[],"class_list":["post-146687","post","type-post","status-publish","format-standard","hentry","category-puebla","tag-14-de-marzo","tag-aspirante","tag-candidato-independiente","tag-hoyesnoticia","tag-hoyesnoticiaapp","tag-ine","tag-juan-alejandro-amoros-herrera","tag-pes","tag-puebla"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/146687"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=146687"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/146687\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=146687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=146687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=146687"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=146687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}