{"id":190146,"date":"2020-02-27T14:01:12","date_gmt":"2020-02-27T20:01:12","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=190146"},"modified":"2020-02-27T14:01:12","modified_gmt":"2020-02-27T20:01:12","slug":"abren-casa-de-salud-en-cuautlancingo","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2020\/02\/27\/abren-casa-de-salud-en-cuautlancingo\/","title":{"rendered":"Abren Casa de Salud en Cuautlancingo"},"content":{"rendered":"<p>A fin de acercar los servicios b\u00e1sicos de <a href=\"https:\/\/sintesis.com.mx\/puebla\/?s=salud\" target=\"_blank\" rel=\"noopener noreferrer\">salud<\/a> a los habitantes de la colonia <strong>Nueva Alemania,<\/strong> ubicada en la junta auxiliar de Sanctorum en el municipio de <a href=\"http:\/\/www.cuautlancingo.gob.mx\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Cuautlancingo<\/strong><\/a>, la alcaldesa de esta demarcaci\u00f3n, <strong>Guadalupe Daniel Hern\u00e1ndez<\/strong> inaugur\u00f3 las instalaciones de la Casa de Salud para esta localidad.<\/p>\n<p>En las instalaciones ubicadas en calle M\u00fanich 18, la alcaldesa llev\u00f3 a cabo el corte de list\u00f3n y se\u00f1al\u00f3 que en este inmueble <strong>se tendr\u00e1n 3 m\u00f3dulos para atenci\u00f3n de consulta b\u00e1sica<\/strong> y vacunaci\u00f3n, adem\u00e1s de control de nutrici\u00f3n para ni\u00f1os y adultos, promoci\u00f3n a la salud, curaciones, planificaci\u00f3n y toma de glucosa, presi\u00f3n y control para diabetes.<\/p>\n<p>En su mensaje, la alcaldesa expres\u00f3 que se ha tenido una visi\u00f3n para brindar estos servicios a todo el municipio, <strong>\u201cestamos trabajando de manera equitativa para las tres juntas auxiliares, <\/strong>queremos acercar los servicios de salud a todos los ciudadanos, por distancia, por tiempos es dif\u00edcil acudir a una atenci\u00f3n, <strong>por ello hoy aperturamos esta casa de Salud<\/strong>, seguimos sumando esfuerzos <strong>para la comunidad en general\u201d.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/Municipios?src=hash&amp;ref_src=twsrc%5Etfw\">#Municipios<\/a> \ud83d\udde3| Encabeza <a href=\"https:\/\/twitter.com\/Lupita_DanielH?ref_src=twsrc%5Etfw\">@Lupita_DanielH<\/a> inauguraci\u00f3n de Casa de Salud en colonia Nueva Alemania en <a href=\"https:\/\/twitter.com\/hashtag\/Cuautlancingo?src=hash&amp;ref_src=twsrc%5Etfw\">#Cuautlancingo<\/a> \ud83d\udcf9 <a href=\"https:\/\/twitter.com\/reporpue11?ref_src=twsrc%5Etfw\">@reporpue11<\/a> <a href=\"https:\/\/t.co\/ASEswUmgg8\">pic.twitter.com\/ASEswUmgg8<\/a><\/p>\n<p>&mdash; S\u00edntesis Puebla (@sintesisweb) <a href=\"https:\/\/twitter.com\/sintesisweb\/status\/1233068546831331329?ref_src=twsrc%5Etfw\">February 27, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>En entrevista, confirm\u00f3 que estar\u00e1n rentando este inmueble para la Casa de Salud y con una inversi\u00f3n de <strong>55 mil pesos<\/strong> para la adquisici\u00f3n de camillas, medicamentos, entre otros \u00a0para beneficiar a m\u00e1s de <strong>2 mil familias que se encuentran en esta zona.<\/strong><\/p>\n<p>Esta se convirti\u00f3 en <strong>la tercera \u00a0Casa de Salud<\/strong> que se han logrado aperturar en el municipio, tal es el caso de <strong>Nuevo Le\u00f3n<\/strong>, en la <strong>Colonia Guadalupe<\/strong> y se plantea abrir una m\u00e1s en <strong>San Lorenzo Almecatla.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En entrevista, confirm\u00f3 que estar\u00e1n rentando este inmueble para la Casa de Salud y con una inversi\u00f3n de 55 mil pesos para la adquisici\u00f3n de camillas, medicamentos, entre otros \u00a0para beneficiar a m\u00e1s de 2 mil familias.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1277,9],"tags":[4293,121,12861,18],"yst_prominent_words":[33958,33957,32161,31372,30373,33956,30892,30176,31706,29620,30148,29781,29745,30155],"class_list":["post-190146","post","type-post","status-publish","format-standard","hentry","category-cuautlancingo","category-municipios","tag-casa-de-salud","tag-cuautlancingo","tag-guadalupe-daniel-hernandez","tag-puebla"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/190146"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=190146"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/190146\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=190146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=190146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=190146"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=190146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}