{"id":214503,"date":"2020-11-24T14:39:10","date_gmt":"2020-11-24T20:39:10","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=214503"},"modified":"2020-11-24T14:39:10","modified_gmt":"2020-11-24T20:39:10","slug":"nombran-barbosa-presidente","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2020\/11\/24\/nombran-barbosa-presidente\/","title":{"rendered":"Nombran a Barbosa como Presidente del Consejo de Conmemoraciones 2021"},"content":{"rendered":"<p>Durante la sesi\u00f3n de <strong>instalaci\u00f3n<\/strong> del <strong>consejo<\/strong> de <strong><a href=\"https:\/\/sintesis.com.mx\/puebla\/2020\/11\/24\/logran-detener-secuestradores\/\">conmemoraciones<\/a> 2021<\/strong>, el <strong>gobernador,<\/strong> <a href=\"https:\/\/twitter.com\/MBarbosaMX?ref_src=twsrc%5Egoogle%7Ctwcamp%5Eserp%7Ctwgr%5Eauthor\"><strong>Luis Miguel Barbosa Huerta<\/strong><\/a>, fue nombrado presidente de este rubro.<\/p>\n<p>En su intervenci\u00f3n, el ejecutivo estatal exalt\u00f3 los 200 a\u00f1os de la Independencia de M\u00e9xico y los 500 a\u00f1os de la resistencia ind\u00edgena.<\/p>\n<p>Mencion\u00f3 que es importante no solamente realizar eventos sino hacer un an\u00e1lisis de dichos acontecimientos para no cometer \u2013desde el gobierno- los mismos errores.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/Gobierno?src=hash&amp;ref_src=twsrc%5Etfw\">#Gobierno<\/a> I El gobernador, <a href=\"https:\/\/twitter.com\/MBarbosaMX?ref_src=twsrc%5Etfw\">@MBarbosaMX<\/a>, encabeza la Sesi\u00f3n de la Instalaci\u00f3n del Consejo de Conmemoraciones 2021 del estado de Puebla e indica que son a\u00f1os cabal\u00edsticos <br \/>\ud83d\udcf9 <a href=\"https:\/\/twitter.com\/lizcervantess?ref_src=twsrc%5Etfw\">@lizcervantess<\/a> <a href=\"https:\/\/t.co\/mogryQtq1u\">pic.twitter.com\/mogryQtq1u<\/a><\/p>\n<p>&mdash; S\u00edntesis Puebla (@sintesisweb) <a href=\"https:\/\/twitter.com\/sintesisweb\/status\/1331290935930609667?ref_src=twsrc%5Etfw\">November 24, 2020<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>\u201cEsto es para se genere un razonamiento a las y los mexicanos sobre su historia\u201d.<\/p>\n<p>El coordinador de memoria hist\u00f3rica y cultural del gobierno federal, Eduardo Villegas Megias, fue testigo de la instalaci\u00f3n, toma de protesta de los vocales y la firma del acta de instalaci\u00f3n del Consejo de Conmemoraciones 2021 del Estado de Puebla.<\/p>\n<p>Coment\u00f3 que se ha dado cumplimiento a uno de los cien compromisos que hizo el presidente de la Rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador, de recuperar la memoria hist\u00f3rica de M\u00e9xico.<\/p>\n<p>\u00abLa historia de lucha por la igualdad nos inspira ahora en este movimiento de la cuarta\u00a0 transformaci\u00f3n pol\u00edtica que impulsa el presidente de la Rep\u00fablica\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la sesi\u00f3n de instalaci\u00f3n del consejo de conmemoraciones 2021, el gobernador, Luis Miguel Barbosa Huerta, fue nombrado presidente de este rubro. En su intervenci\u00f3n, el ejecutivo estatal exalt\u00f3 los 200 a\u00f1os de la Independencia de M\u00e9xico y los 500 a\u00f1os de la resistencia ind\u00edgena. Mencion\u00f3 que es importante no solamente realizar eventos sino hacer [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[48392,63894,41,5389,27,8254,5873,63895,12842,18,8253],"yst_prominent_words":[33497,63893,63891,30302,63890,63888,30081,29786,36373,53853,31514,63889,63887,49815,63892,29626,30887,43468,32512],"class_list":["post-214503","post","type-post","status-publish","format-standard","hentry","category-puebla","tag-al-momento","tag-consejo-de-conmemoraciones-2021","tag-es-noticia","tag-gobernador","tag-hoyesnoticia","tag-hoyesnoticiaapp","tag-luis-miguel-barbosa-huerta","tag-nombran","tag-presidente","tag-puebla","tag-slideapp"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/214503"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=214503"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/214503\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=214503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=214503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=214503"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=214503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}