{"id":226701,"date":"2021-03-11T09:59:53","date_gmt":"2021-03-11T15:59:53","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=226701"},"modified":"2021-03-11T11:14:42","modified_gmt":"2021-03-11T17:14:42","slug":"dif-municipal-entrego-175-apoyos","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2021\/03\/11\/dif-municipal-entrego-175-apoyos\/","title":{"rendered":"DIF municipal recibe 175 solicitudes para gastos de cremaci\u00f3n y ox\u00edgeno"},"content":{"rendered":"<p>Al informar que al corte de este d\u00eda se han entregado 38 apoyos econ\u00f3micos para cremaci\u00f3n y 10 para relleno de tanques de ox\u00edgeno, la directora del DIF municipal, Silvia Jaime Hern\u00e1ndez, dio a conocer que al corte del 10 de marzo, ingresaron un total de 175 solicitudes.<\/p>\n<p>En conferencia con medios de comunicaci\u00f3n informo que es viable contar con recursos extraordinarios para apoyar a personas con problemas econ\u00f3micos por <strong>covid-19<\/strong>.<\/p>\n<p>Desde el 20 de enero, fecha en la que se dieron a conocer los apoyos, han recibido 108 solicitudes para ayuda de cremaci\u00f3n y 67 de tanques de ox\u00edgeno; sin embargo, s\u00f3lo se han beneficiado a 38 familias que cumplieron con los lineamientos.<\/p>\n<p><strong>\u201cSi bien es cierto este recurso se gener\u00f3 de las aportaciones voluntarias, no quisiera comprometer al ayuntamiento, pero seguramente tendremos un recurso extraordinaria si es que se supera la demanda del monto del mill\u00f3n 758 mil\u201d<\/strong>.<\/p>\n<p>Sobre la revisi\u00f3n por parte de la <strong>Auditor\u00eda Superior del Estado (ASE)<\/strong> por los apoyos explic\u00f3 que contribuir\u00e1n a cada requerimiento solicitado, sin embargo, explic\u00f3 que como este proceso no concluye, no se puede iniciar con el procedimiento.<\/p>\n<p><strong>\u201cEste inicio de auditor\u00eda a estos apoyos, puesto que no inici\u00e1bamos solo ten\u00edamos la documentaci\u00f3n del origen del recursos que fue por aportaciones voluntarias, se entreg\u00f3 la documentaci\u00f3n de que no se ha concluido los apoyos, est\u00e1 abierto y no concluye, no puede iniciarse una auditor\u00eda como tal, pero generamos los medios de verificaci\u00f3n, existen lineamientos por contralor\u00eda, est\u00e1n en gobierno abierto y se est\u00e1 cumpliendo con cada uno de lo que solicita\u201d<\/strong>.<\/p>\n<p>Por \u00faltimo, pidi\u00f3 a la poblaci\u00f3n acercarse al DIF para beneficiarse de este programa que a\u00fan sigue y se contempla hasta octubre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al informar que al corte de este d\u00eda se han entregado 38 apoyos econ\u00f3micos para cremaci\u00f3n y 10 para relleno de tanques de ox\u00edgeno, la directora del DIF municipal, Silvia Jaime Hern\u00e1ndez, dio a conocer que al corte del 10 de marzo, ingresaron un total de 175 solicitudes. En conferencia con medios de comunicaci\u00f3n informo [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,93618,3],"tags":[70893,15877,995,69828,736,10113,41,27,8254,70892,70894,58724,23,20668,40526,69538],"yst_prominent_words":[30521,40626,31636,29830,29783,63403,37092,32216,39193,38553,32965,30340,32449,29825,65599],"class_list":["post-226701","post","type-post","status-publish","format-standard","hentry","category-es-noticia","category-foto-reportajes","category-puebla","tag-1-millon-758-mil-pesos","tag-apoyos","tag-ayuntamiento-de-puebla","tag-cremacion","tag-dif","tag-directora","tag-es-noticia","tag-hoyesnoticia","tag-hoyesnoticiaapp","tag-programa-continua","tag-recursos-de-funcionarios","tag-silvia-jaime-hernandez","tag-slide","tag-slider","tag-sliderapp","tag-tanques-de-oxigeno"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/226701"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=226701"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/226701\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=226701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=226701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=226701"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=226701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}