{"id":262089,"date":"2021-11-07T11:49:11","date_gmt":"2021-11-07T17:49:11","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=262089"},"modified":"2021-11-07T15:49:23","modified_gmt":"2021-11-07T21:49:23","slug":"listo-operativo-buen-fin-2","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2021\/11\/07\/listo-operativo-buen-fin-2\/","title":{"rendered":"Listo operativo Buen Fin, anuncia Eduardo Rivera"},"content":{"rendered":"<p>El <strong>ayuntamiento de Puebla pondr\u00e1 en marcha el operativo El Buen Fin<\/strong> este <strong>mi\u00e9rcoles con el objetivo de salvaguardar<\/strong> a la poblaci\u00f3n que realiza compras en este <strong>periodo de descuentos<\/strong>.<\/p>\n<p>En entrevista despu\u00e9s de la <strong>jornada integral en Guadalupe Caleras<\/strong>, el alcalde de <a href=\"https:\/\/sintesis.com.mx\/puebla\/2021\/11\/06\/puebla-capital-encabeza\/\"><strong>Puebla<\/strong><\/a>, <a href=\"https:\/\/twitter.com\/eduardorivera01?ref_src=twsrc%5Egoogle%7Ctwcamp%5Eserp%7Ctwgr%5Eauthor\"><strong>Eduardo Rivera P\u00e9rez<\/strong><\/a>, expuso que estar\u00e1 vigente el programa de acompa\u00f1amiento bancario, por lo que solicit\u00f3 a todo aquel que realice transacciones pedir el apoyo de la polic\u00eda municipal.<\/p>\n<p>Rivera P\u00e9rez dijo que el operativo se realizar\u00e1 de forma interinstitucional, con ediles de la zona metropolitana, empresarios y gobierno del estado.<\/p>\n<p>\u00abEstamos coordinados las \u00e1reas de seguridad metropolitanas, tambi\u00e9n con las plazas comerciales, y estaremos anunciando un operativo de seguridad en el transcurso de la pr\u00f3xima semana, si no mal recuerdo el d\u00eda mi\u00e9rcoles. Estaremos dando a conocer este operativo de manera conjunta para que el todo el buen fin pueda haber la seguridad,\u00a0 sobre todo que es lo que m\u00e1s le preocupa a los empresarios, a las plazas comerciales y por supuesto a los ciudadanos que van a acudir a las compras de este buen fin\u00bb.<\/p>\n<p>Con relaci\u00f3n a los ambulantes, coment\u00f3 que la calle 5 de mayo y la plancha del z\u00f3calo es innegociable, pero ser\u00e1 el secretario de Gobernaci\u00f3n que informe los avances y acuerdos con los vendedores informales.<\/p>\n<p>\u00abLo que se ha comentado,\u00a0 el tema de la vialidad 5 de Mayo, la propia plancha del Z\u00f3calo sigue siendo un \u00e1rea restrictiva, en donde no habra ambulantes y seguimos en este proceso de di\u00e1logo para reubicar la cantidad que falta\u00bb.<\/p>\n<p>En semanas pasadas, Jorge Cruz Lepe mencion\u00f3 que segu\u00eda en pl\u00e1ticas con los l\u00edderes de las agrupaciones pero de inicio explic\u00f3 que buscar\u00e1n una reducci\u00f3n para esas fechas, destacando que usualmente este periodo no es fuerte para ellos sino para las empresas que s\u00ed ofrecen pagos en mensualidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ayuntamiento de Puebla pondr\u00e1 en marcha el operativo El Buen Fin este mi\u00e9rcoles con el objetivo de salvaguardar a la poblaci\u00f3n que realiza compras en este periodo de descuentos. En entrevista despu\u00e9s de la jornada integral en Guadalupe Caleras, el alcalde de Puebla, Eduardo Rivera P\u00e9rez, expuso que estar\u00e1 vigente el programa de acompa\u00f1amiento [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72263,3,11],"tags":[7994,425,19670,76964,356,17718,18,490,23,8253],"yst_prominent_words":[33809,31523,30051,46229,30685,37078,30263,30466,31668,32457,30039,31587,30900,51094,32953,32950,29562,29661,45008,29580],"class_list":["post-262089","post","type-post","status-publish","format-standard","hentry","category-capital","category-puebla","category-slide","tag-acompanamiento-bancario","tag-ayuntamiento","tag-capital","tag-coordinacion-metropolitana","tag-eduardo-rivera-perez","tag-operativo-buen-fin","tag-puebla","tag-seguridad","tag-slide","tag-slideapp"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/262089"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=262089"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/262089\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=262089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=262089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=262089"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=262089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}