{"id":323976,"date":"2022-11-28T16:10:03","date_gmt":"2022-11-28T22:10:03","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=323976"},"modified":"2022-11-28T16:10:03","modified_gmt":"2022-11-28T22:10:03","slug":"proceso-violacion-adolescente","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2022\/11\/28\/proceso-violacion-adolescente\/","title":{"rendered":"Vinculado a proceso por presunta violaci\u00f3n de adolescente en Zaragoza"},"content":{"rendered":"<p>La Fiscal\u00eda General del Estado de Puebla obtuvo la vinculaci\u00f3n a proceso de Alberto N. investigado por su posible responsabilidad en el delito de violaci\u00f3n cometido en contra de una adolescente.<\/p>\n<p>Presuntamente el imputado violent\u00f3 de forma sexual a la v\u00edctima de 17 a\u00f1os de edad, quien era empleada en su tortiller\u00eda.<\/p>\n<p>El hecho ocurri\u00f3 el 15 de noviembre de 2020 en el centro del municipio de Zaragoza. Alberto N. fue detenido y puesto a disposici\u00f3n al ser se\u00f1alado por cometer el il\u00edcito.<\/p>\n<p>Con las pruebas que recab\u00f3 y present\u00f3 la Fiscal\u00eda de Puebla ante el Juez de Control, se dict\u00f3 auto de vinculaci\u00f3n a proceso contra Alberto N. quien permanecer\u00e1 con la medida cautelar de prisi\u00f3n preventiva oficiosa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" jch-lazyloaded\" src=\"https:\/\/fiscalia.puebla.gob.mx\/images\/Fotos_boletines\/Fotos_2022\/Noviembre\/VaP_-_Alberto_N.jpg\" alt=\"VaP Alberto N\" width=\"826\" height=\"464\" data-src=\"\/images\/Fotos_boletines\/Fotos_2022\/Noviembre\/VaP_-_Alberto_N.jpg\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General del Estado de Puebla obtuvo la vinculaci\u00f3n a proceso de Alberto N. investigado por su posible responsabilidad en el delito de violaci\u00f3n cometido en contra de una adolescente. Presuntamente el imputado violent\u00f3 de forma sexual a la v\u00edctima de 17 a\u00f1os de edad, quien era empleada en su tortiller\u00eda. El hecho ocurri\u00f3 [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1285],"tags":[5659,20939,8179],"yst_prominent_words":[32213,30933,29857,29562,41444,49106],"class_list":["post-323976","post","type-post","status-publish","format-standard","hentry","category-justicia","tag-fiscalia","tag-proceso","tag-violacion"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/323976"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=323976"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/323976\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=323976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=323976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=323976"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=323976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}