{"id":330241,"date":"2023-01-16T18:29:59","date_gmt":"2023-01-17T00:29:59","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=330241"},"modified":"2023-01-16T18:29:59","modified_gmt":"2023-01-17T00:29:59","slug":"impulsa-gobierno-de","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2023\/01\/16\/impulsa-gobierno-de\/","title":{"rendered":"Impulsa gobierno de Cholula acciones en favor de la ni\u00f1ez"},"content":{"rendered":"<p>Comprometida con la formaci\u00f3n integral de las y los ni\u00f1os cholultecas, la Presidenta Municipal de San Pedro Cholula, Paola Angon, contin\u00faa gestionando acciones e infraestructura para brindar educaci\u00f3n de calidad y procurar un sano desarrollo, con mejores condiciones para la ni\u00f1ez. Es por ello, que se hizo entrega de infraestructura en la primaria \u201cEmiliano Zapata\u201d, de San Juan Tlautla, y se inici\u00f3 con el programa \u201cAbrazando la Infancia\u201d.<\/p>\n<p>En primera instancia, este lunes, Angon Silva hizo entrega de la barda perimetral en la escuela primaria de dicha junta auxiliar, la cual tuvo una inversi\u00f3n superior a 1.2 millones de pesos de recursos federales, mismos que fueron destinados con la intenci\u00f3n de procurar una infraestructura duradera para que muchas generaciones puedan aprovecharla.<\/p>\n<p>Como parte de la inauguraci\u00f3n de la barda perimetral la presidenta PaolaAngon, agradeci\u00f3 la presencia del personal docente, padres de familia, representantes de la Secretar\u00eda de Educaci\u00f3n P\u00fablica; adem\u00e1s de Regidores y servidores p\u00fablicos, a quienes les expres\u00f3 su alegr\u00eda al entregar los 270 metros cuadrados de barda, que incluyen port\u00f3n y puerta, lo que reforzar\u00e1 la seguridad en la primaria y generar\u00e1 tranquilidad a los alumnos, as\u00ed como a los padres de familia.<\/p>\n<p>\u201cDeseo que pasen momentos felices aqu\u00ed y que sus pap\u00e1s tengan la tranquilidad de saber que ustedes est\u00e1n protegidos y bien resguardados en esta instituci\u00f3n\u201d, indic\u00f3 Paola Angon y agreg\u00f3 que los mejores espacios en las escuelas son indispensables para un mejor presente y futuro.<\/p>\n<p>Por su parte, la Directora Wendy L\u00f3pez Luna detall\u00f3 que esta es una inversi\u00f3n hist\u00f3rica en los m\u00e1s de 50 a\u00f1os de vida de la instituci\u00f3n, y que adem\u00e1s beneficia a la supervisi\u00f3n escolar, asentada en sus instalaciones; \u201cEsta obra evita accidentes ya que anteriormente estaba en deterioro, nos llena de satisfacci\u00f3n el ser beneficiarios de apoyos que mejoran las condiciones educativas de la escuela primaria\u201d refiri\u00f3.<\/p>\n<p>A esta mejora estructural en el plantel, seg\u00fan explic\u00f3 el Secretario de Infraestructura y Servicios P\u00fablicos Generales, Carlos Carpinteyro, se a\u00f1adi\u00f3 la construcci\u00f3n de una cisterna para la captaci\u00f3n de agua pluvial, acci\u00f3n que se logr\u00f3 trabajando de la mano -gobierno y sociedad-, derivado de una petici\u00f3n recibida durante el programa de Martes Ciudadanos, siendo gestionada por parte del gobierno la mano de obra y maquinaria para su realizaci\u00f3n; por su parte el comit\u00e9 de padres de familia aport\u00f3 con los materiales, dando como resultado un trabajo colaborativo en beneficio de los estudiantes.<\/p>\n<p>Arranca \u201cAbrazando a la infancia\u201d por parte del DIF Por otra parte, en favor de la salud -a trav\u00e9s del DIF Cholula- y acompa\u00f1ada por la Presidenta Honoraria Mar\u00eda de la Barreda, la<br \/>\nPresidenta Municipal inici\u00f3 la entrega de m\u00e1s de 4 mil prendas abrigadoras para ni\u00f1as y ni\u00f1os de entre 3 y 6 a\u00f1os de edad, en edad preescolar.<\/p>\n<p>Los chalecos ser\u00e1n entregados a peque\u00f1os de 16 preescolares p\u00fablicos y 15 Centros de Asistencia Infantil Comunitario (CAIC) en el municipio. \u00abSabemos que ustedes, como peque\u00f1os, son los m\u00e1s afectados por el fr\u00edo: no les gusta abrigarse porque a veces les estorba su chamarra, pero esta prenda abrigadora est\u00e1 muy bien pensada para la comodidad de todos ustedes\u00bb, recalc\u00f3 en su mensaje la Presidenta Honoraria del DIF Cholula.<\/p>\n<p>Por su parte, la Presidenta Paola Angon destac\u00f3 la importancia de arrancar con el programa \u00abAbrazando la Infancia\u00bb que surge como respuesta a la necesidad de proteger con una prenda la salud de los peque\u00f1os, agradeciendo la disposici\u00f3n del regidor David Castellanos y el Cabildo para trabajar conjuntamente en beneficio de los grupos m\u00e1s vulnerables.<\/p>\n<p>En los eventos tambi\u00e9n estuvieron presentes los regidores David Castellanos, Fabiola Torres, Ram\u00f3n Blanca, Sandra Hern\u00e1ndez Romano y el s\u00edndico municipal Carlos Bojalil.<\/p>\n<p>De esta manera, cumpliendo con el compromiso de brindar herramientas para un mejor desarrollo en el entorno educativo y la salud de la infancia, el Gobierno de Cholula contin\u00faa trabajando para acercar beneficios a las ni\u00f1as y ni\u00f1os cholultecas.<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a5762b3bc6fe  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a5762b3bc6fe  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a5762b3bc6fe  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a5762b3bc6fe  .td-doubleSlider-2 .td-item4 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a5762b3bc6fe  .td-doubleSlider-2 .td-item5 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a5762b3bc6fe  .td-doubleSlider-2 .td-item6 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a5762b3bc6fe  .td-doubleSlider-2 .td-item7 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a5762b3bc6fe\" class=\"td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> of 7<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4.jpeg\" title=\"WhatsApp Image 2023-01-16 at 6.15.26 PM (4)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4-630x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4-630x420.jpeg 630w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4-300x200.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4-1024x682.jpeg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4-768x512.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4-696x464.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4-1068x712.jpeg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-4.jpeg 1280w\" sizes=\"(max-width: 630px) 100vw, 630px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3.jpeg\" title=\"WhatsApp Image 2023-01-16 at 6.15.26 PM (3)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3-630x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3-630x420.jpeg 630w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3-300x200.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3-1024x682.jpeg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3-768x512.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3-1536x1023.jpeg 1536w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3-696x464.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3-1068x712.jpeg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-3.jpeg 1600w\" sizes=\"(max-width: 630px) 100vw, 630px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2.jpeg\" title=\"WhatsApp Image 2023-01-16 at 6.15.26 PM (2)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2-749x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2-749x420.jpeg 749w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2-300x168.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2-1024x574.jpeg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2-768x431.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2-696x390.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2-1068x599.jpeg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-2.jpeg 1280w\" sizes=\"(max-width: 749px) 100vw, 749px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item4\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1.jpeg\" title=\"WhatsApp Image 2023-01-16 at 6.15.26 PM (1)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1-630x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1-630x420.jpeg 630w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1-300x200.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1-1024x683.jpeg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1-768x512.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1-696x464.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1-1068x712.jpeg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1.jpeg 1212w\" sizes=\"(max-width: 630px) 100vw, 630px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item5\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM.jpeg\" title=\"WhatsApp Image 2023-01-16 at 6.15.26 PM\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-748x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-748x420.jpeg 748w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-300x168.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1024x575.jpeg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-768x431.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1536x862.jpeg 1536w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-696x391.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM-1068x599.jpeg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.26-PM.jpeg 1600w\" sizes=\"(max-width: 748px) 100vw, 748px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item6\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2.jpeg\" title=\"WhatsApp Image 2023-01-16 at 6.15.25 PM (2)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2-748x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2-748x420.jpeg 748w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2-300x168.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2-1024x575.jpeg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2-768x431.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2-1536x862.jpeg 1536w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2-696x391.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2-1068x599.jpeg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-2.jpeg 1600w\" sizes=\"(max-width: 748px) 100vw, 748px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item7\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1.jpeg\" title=\"WhatsApp Image 2023-01-16 at 6.15.25 PM (1)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1-748x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1-748x420.jpeg 748w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1-300x168.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1-1024x575.jpeg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1-768x431.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1-1536x862.jpeg 1536w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1-696x391.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1-1068x599.jpeg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-16-at-6.15.25-PM-1.jpeg 1600w\" sizes=\"(max-width: 748px) 100vw, 748px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item4\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item5\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item6\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item7\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n","protected":false},"excerpt":{"rendered":"<p>Comprometida con la formaci\u00f3n integral de las y los ni\u00f1os cholultecas, la Presidenta Municipal de San Pedro Cholula, Paola Angon, contin\u00faa gestionando acciones e infraestructura para brindar educaci\u00f3n de calidad y procurar un sano desarrollo, con mejores condiciones para la ni\u00f1ez. Es por ello, que se hizo entrega de infraestructura en la primaria \u201cEmiliano Zapata\u201d, [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":330244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82857],"tags":[41,27,8254,437],"yst_prominent_words":[40813,30798,53825,29679,31679,30598,29916,30361,37801,30866,47351],"class_list":["post-330241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-san-pedro-cholula","tag-es-noticia","tag-hoyesnoticia","tag-hoyesnoticiaapp","tag-san-pedro-cholula"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/330241"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=330241"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/330241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media\/330244"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=330241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=330241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=330241"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=330241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}