{"id":360002,"date":"2023-07-12T15:30:53","date_gmt":"2023-07-12T21:30:53","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=360002"},"modified":"2023-07-12T15:39:33","modified_gmt":"2023-07-12T21:39:33","slug":"armenta-alianzas-mundiales","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2023\/07\/12\/armenta-alianzas-mundiales\/","title":{"rendered":"Armenta genera alianzas con potencias mundiales a favor de M\u00e9xico, recibe al vicepresidente del Comit\u00e9 Permanente de la Asamblea Popular China, Xiao Jie"},"content":{"rendered":"<p>El senador de Morena, Alejandro Armenta asever\u00f3 que M\u00e9xico vive una etapa de desarrollo y modernizaci\u00f3n impulsada por el presidente de la Rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador, la cual har\u00e1 que nuestro pa\u00eds alcance la soberan\u00eda energ\u00e9tica en los pr\u00f3ximos meses, lo que ser\u00e1 importante para la atracci\u00f3n de inversiones.<\/p>\n<p><strong>En compa\u00f1\u00eda del presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica del Senado, Eduardo Ram\u00edrez Aguilar, sostuvo un encuentro con el vicepresidente del Comit\u00e9 Permanente de la Asamblea Popular China, Xiao Jie.<\/strong><\/p>\n<p>El Presidente del Senado, Alejandro Armenta destac\u00f3 que el continente tendr\u00e1 un nuevo canal el pr\u00f3ximo a\u00f1o cuando entre en funcionamiento el tren interoce\u00e1nico, una red ferroviaria que comunicar\u00e1 el Oc\u00e9ano Pac\u00edfico con el Atl\u00e1ntico y permitir\u00e1 acercar comercialmente a Europa y Asia con Latinoam\u00e9rica.<\/p>\n<p>El legislador poblano remarc\u00f3 que ambas naciones comparten los objetivos de la Agenda 2030 para el desarrollo sostenible, por lo que nuestro gobierno ha realizado la inversi\u00f3n m\u00e1s grande en su historia en materia de rescate de sus bosques y reforestaci\u00f3n, adem\u00e1s de que estableci\u00f3 la rector\u00eda del litio.<\/p>\n<p>A su vez, el presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica del Senado, Eduardo Ram\u00edrez Aguilar, afirm\u00f3 que nuestros objetivos son coincidentes y descansan en una visi\u00f3n compartida sobre los beneficios del comercio y la inversi\u00f3n, como factores esenciales de una econom\u00eda que mejore la calidad de vida de sus ciudadanos.<\/p>\n<p>La presencia de Xiao Jie proporciona una gran oportunidad para dialogar de manera abierta y hacer m\u00e1s provechosa la amistad que se profesan nuestros pueblos, as\u00ed como hacer llegar una invitaci\u00f3n del Congreso Mexicano para que el presidente de la Republica Popular China, Xi Jinping, visite nuestra naci\u00f3n el pr\u00f3ximo a\u00f1o.<\/p>\n<p>Xiao Jie, vicepresidente del Comit\u00e9 Permanente de la Asamblea Popular Nacional de China, reconoci\u00f3 y agradeci\u00f3 al senador Alejandro Armenta por impulsar la cooperaci\u00f3n entre ambas naciones.<\/p>\n<p>Destac\u00f3 que en 2023 se cumplen 10 a\u00f1os de la Asociaci\u00f3n Estrat\u00e9gica Integral de China y M\u00e9xico. <strong>\u201cEl \u00e1rbol de amistad entre China y M\u00e9xico ya es frondoso y fruct\u00edfero trayendo intereses reales a ambos pueblos\u201d,<\/strong> expres\u00f3.<\/p>\n<p><strong>\u201cLos intercambios e interacciones en distintos niveles y en diversos campos son frecuentes, con una confianza mutua muy profunda, y los intercambios entre los \u00f3rganos legislativos entre ambos pa\u00edses han mantenido los intercambios estrechos, contribuyendo as\u00ed a los cambios profundos de las federaciones chinas y mexicanas\u201d,<\/strong> asent\u00f3.<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a56f8ed206d1  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.04-PM-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a56f8ed206d1  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-4-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a56f8ed206d1  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-2-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a56f8ed206d1  .td-doubleSlider-2 .td-item4 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-3-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a56f8ed206d1  .td-doubleSlider-2 .td-item5 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-1-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a56f8ed206d1  .td-doubleSlider-2 .td-item6 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a56f8ed206d1  .td-doubleSlider-2 .td-item7 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-1-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a56f8ed206d1  .td-doubleSlider-2 .td-item8 {\r\n                        background: url(https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a56f8ed206d1\" class=\"td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> of 8<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.04-PM.jpeg\" title=\"WhatsApp Image 2023-07-12 at 3.19.04 PM\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.04-PM-752x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.04-PM-752x420.jpeg 752w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.04-PM-300x168.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.04-PM-768x429.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.04-PM-696x389.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.04-PM.jpeg 1024w\" sizes=\"(max-width: 752px) 100vw, 752px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-4.jpeg\" title=\"WhatsApp Image 2023-07-12 at 3.19.03 PM (4)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-4-694x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-4-694x420.jpeg 694w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-4-300x182.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-4-768x465.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-4-696x421.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-4.jpeg 1024w\" sizes=\"(max-width: 694px) 100vw, 694px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-2.jpeg\" title=\"WhatsApp Image 2023-07-12 at 3.19.03 PM (2)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-2-664x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-2-664x420.jpeg 664w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-2-300x190.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-2-768x486.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-2-696x440.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-2.jpeg 1024w\" sizes=\"(max-width: 664px) 100vw, 664px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item4\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-3.jpeg\" title=\"WhatsApp Image 2023-07-12 at 3.19.03 PM (3)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-3-743x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-3-743x420.jpeg 743w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-3-300x170.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-3-768x434.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-3-696x394.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-3.jpeg 1024w\" sizes=\"(max-width: 743px) 100vw, 743px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item5\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-1.jpeg\" title=\"WhatsApp Image 2023-07-12 at 3.19.03 PM (1)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-1-749x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-1-749x420.jpeg 749w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-1-300x168.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-1-768x431.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-1-696x390.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-1.jpeg 1024w\" sizes=\"(max-width: 749px) 100vw, 749px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item6\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM.jpeg\" title=\"WhatsApp Image 2023-07-12 at 3.19.03 PM\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-714x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-714x420.jpeg 714w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-300x176.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-768x452.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM-696x409.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.19.03-PM.jpeg 1024w\" sizes=\"(max-width: 714px) 100vw, 714px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item7\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-1.jpeg\" title=\"WhatsApp Image 2023-07-12 at 3.17.45 PM (1)\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-1-748x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-1-748x420.jpeg 748w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-1-300x168.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-1-768x431.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-1-696x391.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-1.jpeg 1024w\" sizes=\"(max-width: 748px) 100vw, 748px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item8\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM.jpeg\" title=\"WhatsApp Image 2023-07-12 at 3.17.45 PM\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-748x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-748x420.jpeg 748w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-300x168.jpeg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-768x431.jpeg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM-696x391.jpeg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-12-at-3.17.45-PM.jpeg 1024w\" sizes=\"(max-width: 748px) 100vw, 748px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item4\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item5\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item6\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item7\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item8\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n","protected":false},"excerpt":{"rendered":"<p>El senador de Morena, Alejandro Armenta asever\u00f3 que M\u00e9xico vive una etapa de desarrollo y modernizaci\u00f3n impulsada por el presidente de la Rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador, la cual har\u00e1 que nuestro pa\u00eds alcance la soberan\u00eda energ\u00e9tica en los pr\u00f3ximos meses, lo que ser\u00e1 importante para la atracci\u00f3n de inversiones. En compa\u00f1\u00eda del presidente de [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":360009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[3569,41,27,8254,18,8253,20668,40526],"yst_prominent_words":[48633,39511,32618],"class_list":["post-360002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","tag-china","tag-es-noticia","tag-hoyesnoticia","tag-hoyesnoticiaapp","tag-puebla","tag-slideapp","tag-slider","tag-sliderapp"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/360002"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=360002"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/360002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media\/360009"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=360002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=360002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=360002"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=360002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}