{"id":402057,"date":"2024-04-10T10:22:11","date_gmt":"2024-04-10T16:22:11","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=402057"},"modified":"2024-04-12T10:27:34","modified_gmt":"2024-04-12T16:27:34","slug":"los-acuiferos-del","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2024\/04\/10\/los-acuiferos-del\/","title":{"rendered":"Los acu\u00edferos del mundo se est\u00e1n agotando y su calidad deteriorando"},"content":{"rendered":"<p class=\"rtejustify\"><strong>Si bien el 70 por ciento de la superficie del planeta es agua, s\u00f3lo 2.5 por ciento es dulce o de baja salinidad (el resto es salada)<\/strong>, fundamental para la supervivencia de los organismos vivos. De \u00e9sta, cerca de dos tercios est\u00e1n congeladas y en la humedad del suelo, el 30.3 por ciento en los acu\u00edferos o r\u00edos subterr\u00e1neos, y poco menos del 0.3 por ciento en la superficie, en lagos, arroyos, r\u00edos y humedales.\u00a0<strong>De aqu\u00ed la importancia de proteger estas aguas subterr\u00e1neas.<\/strong><\/p>\n<p class=\"rtejustify\">Lo anterior durante la conferencia<strong> Perspectivas Globales sobre la P\u00e9rdida y Recuperaci\u00f3n de Aguas Subterr\u00e1neas: Una Aproximaci\u00f3n Comparativa desde Puebla<\/strong>, <strong>impartida por el doctor Pedro Francisco Rodr\u00edguez Espinosa, director del Centro Interdisciplinario de Investigaciones y Estudios sobre Medio Ambiente y Desarrollo, del IPN<\/strong>, organizada por la <strong>Coordinaci\u00f3n de Gesti\u00f3n Ambiental de la Coordinaci\u00f3n General de Desarrollo Sustentable de la BUAP.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-402058\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/9-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/9-1-300x200.jpg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/9-1-1024x683.jpg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/9-1-768x512.jpg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/9-1-1536x1024.jpg 1536w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/9-1-2048x1365.jpg 2048w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/9-1-696x464.jpg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/9-1-1068x712.jpg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/9-1-630x420.jpg 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p class=\"rtejustify\">Al respecto, hizo referencia a estudios cient\u00edficos a nivel mundial en los que se alerta sobre el gran declive de la reserva de agua subterr\u00e1nea, pues hay una disminuci\u00f3n generalizada en los acu\u00edferos, lo que resulta en la intrusi\u00f3n de agua de mar, hundimiento de la tierra, agotamiento de los caudales y pozos secos.<\/p>\n<p class=\"rtejustify\">Para el caso de M\u00e9xico, se\u00f1al\u00f3 que el volumen concesionado de agua subterr\u00e1nea, <strong>de extracci\u00f3n mediante pozos, el sector agr\u00edcola representa el 76 por ciento (CONAGUA 2018)<\/strong> y el resto es para el abastecimiento p\u00fablico, seguido de la industria y la energ\u00eda el\u00e9ctrica (no incluye hidroel\u00e9ctricas). Es decir, el mayor volumen de agua que se extrae se utiliza para regar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-402059\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/10-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/10-1-300x200.jpg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/10-1-1024x683.jpg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/10-1-768x512.jpg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/10-1-1536x1024.jpg 1536w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/10-1-2048x1365.jpg 2048w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/10-1-696x464.jpg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/10-1-1068x712.jpg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/10-1-630x420.jpg 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p class=\"rtejustify\">El especialista agreg\u00f3 que lo alarmante es que \u201cestamos sacando m\u00e1s agua de los acu\u00edferos de lo que estamos recargando o regresando a los mismos, agot\u00e1ndonos el recurso y adem\u00e1s creando conos de depresi\u00f3n o abatimiento\u201d.<\/p>\n<p class=\"rtejustify\"><strong>Rodr\u00edguez Espinosa concluy\u00f3 que la cantidad de agua subterr\u00e1nea en el mundo se est\u00e1 agotando y su calidad deteriorando.<\/strong> Al reconocer que la gesti\u00f3n sostenible de los recursos h\u00eddricos atraviesa una situaci\u00f3n dif\u00edcil, resalt\u00f3 el valor de las investigaciones en la materia, <strong>pues la informaci\u00f3n cient\u00edfica puede dictar nuevas pol\u00edticas p\u00fablicas para la explotaci\u00f3n de los recursos h\u00eddricos subterr\u00e1neos.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-402060\" src=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/11-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/11-300x200.jpg 300w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/11-1024x683.jpg 1024w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/11-768x512.jpg 768w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/11-1536x1024.jpg 1536w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/11-2048x1365.jpg 2048w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/11-696x464.jpg 696w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/11-1068x712.jpg 1068w, https:\/\/sintesis.com.mx\/puebla\/wp-content\/uploads\/2024\/04\/11-630x420.jpg 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si bien el 70 por ciento de la superficie del planeta es agua, s\u00f3lo 2.5 por ciento es dulce o de baja salinidad (el resto es salada), fundamental para la supervivencia de los organismos vivos. De \u00e9sta, cerca de dos tercios est\u00e1n congeladas y en la humedad del suelo, el 30.3 por ciento en los [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":402058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46847],"tags":[41,47256,27,8254],"yst_prominent_words":[33277,31030,29944,30276,32625,29923,39173,30476,34046,36010,29768,31790,42721],"class_list":["post-402057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esfera-universitaria","tag-es-noticia","tag-esfera-universitaria","tag-hoyesnoticia","tag-hoyesnoticiaapp"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/402057"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=402057"}],"version-history":[{"count":1,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/402057\/revisions"}],"predecessor-version":[{"id":402061,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/402057\/revisions\/402061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media\/402058"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=402057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=402057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=402057"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=402057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}