{"id":408598,"date":"2024-05-23T11:51:07","date_gmt":"2024-05-23T17:51:07","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=408598"},"modified":"2024-05-23T11:51:07","modified_gmt":"2024-05-23T17:51:07","slug":"congreso-puebla-otorga","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2024\/05\/23\/congreso-puebla-otorga\/","title":{"rendered":"Congreso de Puebla otorga licencia por tiempo indefinido a Jorge Estefan y Adolfo Alatriste"},"content":{"rendered":"<p>Con 33 votos a favor,<strong> el Congreso del Estado aprob\u00f3 la licencia indefinida y mayor a 30 d\u00edas de Jorge Estafan Chidiac, por lo que se pidi\u00f3 llamar a su suplente para que tome su lugar.<\/strong><\/p>\n<p>En sesi\u00f3n ordinaria, pas\u00f3 lo mismo con el legislador Adolfo Alatriste Cant\u00fa, por lo que su sustituto ingresar\u00e1 en su lugar el pr\u00f3ximo martes 28 de mayo.<\/p>\n<p>Y es que el Tribunal Electoral del Poder judicial de la Federaci\u00f3n (TEPJF), instruy\u00f3 al poder legislativo tomar protesta al suplente de Estefan Chidiac, actual secretario de educaci\u00f3n.<\/p>\n<p>Por dicho cargo, abandon\u00f3 la curul, sin embargo, su permiso era menor a 30 d\u00edas lo que imped\u00eda llegar a Ambrosio Corona Carbar\u00edn, de tal suerte que \u00e9ste interpuso un juicio para la protecci\u00f3n de sus derechos pol\u00edticos ante el m\u00e1ximo \u00f3rgano, mismo que le concedi\u00f3 la raz\u00f3n.<\/p>\n<p>Sobre ello, el presidente del Congreso del Estado Edgar Garmendia sostuvo que no fue una omisi\u00f3n del poder legislativo, ya que respetaron los derechos de los diputados que solicitaron licencia menor a los 31 d\u00edas.<\/p>\n<p>Finalmente, la diputada ex priista y actual coordinadora del Grupo Plural, Silvia Tanus neg\u00f3 que sea un rev\u00e9s al legislativo.<\/p>\n<p>\u201cNo es un rev\u00e9s para nadie, se inconform\u00f3 la persona, como yo me inconform\u00e9 contra una expulsi\u00f3n injusta, no gana ni pierde nadie, gana la justicia que es el tribunal y qu\u00e9 bueno\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con 33 votos a favor, el Congreso del Estado aprob\u00f3 la licencia indefinida y mayor a 30 d\u00edas de Jorge Estafan Chidiac, por lo que se pidi\u00f3 llamar a su suplente para que tome su lugar. En sesi\u00f3n ordinaria, pas\u00f3 lo mismo con el legislador Adolfo Alatriste Cant\u00fa, por lo que su sustituto ingresar\u00e1 en [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":385955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[87931,1960,69961,41,65,27,8254,328,87932,187],"yst_prominent_words":[29570,31230,29787,31121,39151,32964,30240,30447,30688,33949,66230,37007,34553],"class_list":["post-408598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puebla","tag-adolfo-garcia-cantu","tag-congreso-del-estado","tag-edgar-garmendia-de-los-santos","tag-es-noticia","tag-esnoticia","tag-hoyesnoticia","tag-hoyesnoticiaapp","tag-jorge-estefan-chidiac","tag-licencias-definitivas","tag-pri"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/408598"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=408598"}],"version-history":[{"count":3,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/408598\/revisions"}],"predecessor-version":[{"id":408628,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/408598\/revisions\/408628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media\/385955"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=408598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=408598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=408598"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=408598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}