{"id":443797,"date":"2025-02-02T20:40:39","date_gmt":"2025-02-03T02:40:39","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=443797"},"modified":"2025-02-02T20:40:39","modified_gmt":"2025-02-03T02:40:39","slug":"coordinacion-subordinacion-no-claudia-sheinbaum","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2025\/02\/02\/coordinacion-subordinacion-no-claudia-sheinbaum\/","title":{"rendered":"Coordinaci\u00f3n s\u00ed, subordinaci\u00f3n no: Claudia Sheinbaum"},"content":{"rendered":"<p>Ciudad de M\u00e9xico a 2 de febrero de 2025.- Ante la imposici\u00f3n de aranceles por parte del Gobierno de los Estados Unidos, la Presidenta Claudia Sheinbaum Pardo puntualiz\u00f3 que M\u00e9xico no busca una confrontaci\u00f3n, sino que parte de la colaboraci\u00f3n y del trabajo conjunto, por lo que reiter\u00f3 al presidente de EUA, Donald Trump, la propuesta de establecer una mesa de trabajo entre ambos pa\u00edses en materia de seguridad y de salud p\u00fablica, pero siempre con respeto a la soberan\u00eda nacional.<\/p>\n<p>\u201cM\u00e9xico no quiere confrontaci\u00f3n, partimos de la colaboraci\u00f3n entre pa\u00edses vecinos, M\u00e9xico no s\u00f3lo no quiere que el fentanilo no llegue a Estados Unidos, sino que no queremos que llegue a ninguna parte. Por ello, si Estados Unidos quiere combatir a los grupos delictivos y quiere que lo hagamos conjuntamente, debemos trabajar de forma integral, pero siempre bajo principios. Los principios de responsabilidad compartida; de confianza mutua; de colaboraci\u00f3n; y sobre todo, respeto a la soberan\u00eda. La soberan\u00eda no es negociable. Coordinaci\u00f3n s\u00ed, subordinaci\u00f3n no\u201d<\/p>\n<p>\u201cPara ello el d\u00eda de ayer, en mi comunicado, le propuse al Presidente Trump, que establezcamos una mesa de trabajo con nuestros mejores equipos, el de seguridad y tambi\u00e9n el de salud p\u00fablica. No es con imposici\u00f3n de los aranceles como se resuelven los problemas, sino hablando y dialogando como lo hicimos, esto se los quiero contar, lo hicimos as\u00ed en las \u00faltimas semanas, con el Departamento de Estado para atender el fen\u00f3meno de la migraci\u00f3n. En nuestro caso, siempre con el respeto a los derechos humanos\u201d, destac\u00f3 a trav\u00e9s de un video publicado en sus redes sociales.<\/p>\n<p>Desde Palacio Nacional, la Jefa del Ejecutivo Federal rechaz\u00f3 categ\u00f3ricamente la calumnia hecha por La Casa Blanca de que el Gobierno de M\u00e9xico tiene alianzas con organizaciones criminales, as\u00ed como cualquier intenci\u00f3n injerencista en territorio nacional.<\/p>\n<p>\u201cRechazamos categ\u00f3ricamente la calumnia que hace La Casa Blanca al Gobierno de M\u00e9xico, de tener alianzas con organizaciones criminales, as\u00ed como cualquier intenci\u00f3n injerencista en nuestro territorio. La soberan\u00eda no se negocia. Si en alg\u00fan lugar existe tal alianza, es en las armer\u00edas de los Estados Unidos, que venden armas de alto poder, s\u00ed de alto poder, que son de uso exclusivo del ej\u00e9rcito de ellos, a estos grupos criminales. Esto lo demostr\u00f3, el propio Departamento de Justicia de Estados Unidos el 8 de enero de este a\u00f1o\u201d, detall\u00f3.<\/p>\n<p>Como prueba de ello, expuso que la Evaluaci\u00f3n Nacional del Comercio y Tr\u00e1fico de Armas de Fuego (NFCTA, por sus siglas ingl\u00e9s) de la Agencia de Alcohol, Tabaco, Armas de Fuego y Explosivos (ATF, por sus siglas en ingl\u00e9s) del Departamento de Justicia de Estados Unidos, reconoce que el 74 por ciento de las armas que usa la delincuencia organizada en M\u00e9xico proviene de forma ilegal de la industria militar estadounidense.<\/p>\n<p>Resalt\u00f3 que el Gobierno de M\u00e9xico tiene una Estrategia Nacional de Seguridad, que atiende las causas y combate la impunidad, la cual en cuatro meses ha asegurado 40 toneladas de droga, incluyendo 20 millones de dosis de fentanilo. Adem\u00e1s, de que se ha detenido a m\u00e1s de 10 mil personas vinculadas con estos grupos.<\/p>\n<p>En su mensaje, invit\u00f3 al gobierno de Estados Unidos a focalizar sus esfuerzos e inteligencia en el combate a la venta de estupefacientes en las calles de sus principales ciudades y agreg\u00f3 que la epidemia de opioides sint\u00e9ticos en EUA tuvo su origen en la prescripci\u00f3n indiscriminada de medicamentos de este tipo cuya venta contin\u00faa autorizada en las farmacias estadounidenses.<\/p>\n<p>\u201cEl consumo y la distribuci\u00f3n de drogas est\u00e1 en su pa\u00eds y ese es un problema de salud p\u00fablica que no han atendido. \u00bfPor qu\u00e9 no se preguntan cu\u00e1l es la raz\u00f3n de fondo de tanto consumo de drogas que lleva tanto tiempo en Estados Unidos?\u201d, cuestion\u00f3.<\/p>\n<p>La mandataria le asegur\u00f3 a las mexicanas y mexicanos que viven en los Estados Unidos que cuentan con la Presidenta de M\u00e9xico y con un pueblo entero que los defiende y si desean regresar ser\u00e1n recibidos con los brazos abiertos.<\/p>\n<p>\u201cEl pueblo de M\u00e9xico es valiente y tiene mucha dignidad. Es el pueblo m\u00e1s maravilloso que hay sobre la tierra. Les digo que aqu\u00ed est\u00e1 su Presidenta, tenemos valent\u00eda y grandeza, pero siempre, como lo he dicho en otras ocasiones, hay que actuar con la cabeza fr\u00eda y el amor al pueblo\u201d, resalt\u00f3.<\/p>\n<p>Por ello, pidi\u00f3 al pueblo esperar la respuesta del presidente Trump a la propuesta que realiz\u00f3 el Gobierno de M\u00e9xico y adelant\u00f3 que en \u201cLa ma\u00f1anera del pueblo\u201d de este lunes, informar\u00e1 las primeras medidas del Plan B, en respuesta a la imposici\u00f3n de aranceles.<\/p>\n<p>\u201cComo dec\u00eda Ju\u00e1rez: nada por la fuerza, todo por la raz\u00f3n y el derecho. Y entre los individuos, como entre las naciones, el respeto al derecho ajeno es la paz\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico a 2 de febrero de 2025.- Ante la imposici\u00f3n de aranceles por parte del Gobierno de los Estados Unidos, la Presidenta Claudia Sheinbaum Pardo puntualiz\u00f3 que M\u00e9xico no busca una confrontaci\u00f3n, sino que parte de la colaboraci\u00f3n y del trabajo conjunto, por lo que reiter\u00f3 al presidente de EUA, Donald Trump, la [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":443798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87367],"tags":[41,65,27,3598,18,23,20668,40526],"yst_prominent_words":[30513,35231,32829,33948,32957,29626,37752,30135],"class_list":["post-443797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacion","tag-es-noticia","tag-esnoticia","tag-hoyesnoticia","tag-nacion","tag-puebla","tag-slide","tag-slider","tag-sliderapp"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/443797"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=443797"}],"version-history":[{"count":1,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/443797\/revisions"}],"predecessor-version":[{"id":443799,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/443797\/revisions\/443799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media\/443798"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=443797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=443797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=443797"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=443797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}