{"id":455759,"date":"2025-05-07T15:56:32","date_gmt":"2025-05-07T21:56:32","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=455759"},"modified":"2025-05-07T15:56:32","modified_gmt":"2025-05-07T21:56:32","slug":"coronango-rio-atoyac","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2025\/05\/07\/coronango-rio-atoyac\/","title":{"rendered":"Coronango refuerza acciones para rescatar el R\u00edo Atoyac"},"content":{"rendered":"<p class=\"\" data-start=\"61\" data-end=\"352\">El presidente municipal de Coronango, Armando Aguirre Amaro, confirma que mantiene una estrecha relaci\u00f3n de trabajo con el coordinador del Plan H\u00eddrico de Puebla, Raymundo Atanacio Luna, con el objetivo de impulsar el rescate del R\u00edo Atoyac, uno de los afluentes m\u00e1s contaminados del estado.<\/p>\n<p class=\"\" data-start=\"354\" data-end=\"703\">El alcalde detalla que Coronango fue uno de los primeros municipios en sumarse a este esfuerzo estatal. Como primera acci\u00f3n, se llev\u00f3 a cabo una jornada de limpieza en las laderas del r\u00edo, particularmente en la zona de Misiones de San Francisco. Sin embargo, aclara que estas labores apenas marcan el inicio de una estrategia m\u00e1s amplia y constante.<\/p>\n<p class=\"\" data-start=\"705\" data-end=\"966\">Actualmente, el municipio mantiene vigilancia en las zonas donde operan empresas cercanas al afluente, para evitar que viertan desechos en el cauce. Aguirre tambi\u00e9n hace un llamado a la ciudadan\u00eda a denunciar cualquier acto que ponga en riesgo la salud del r\u00edo.<\/p>\n<p class=\"\" data-start=\"968\" data-end=\"1152\">\u201cTuvimos una pl\u00e1tica con Raymundo, ya tocamos el tema de c\u00f3mo vamos a apoyar, qu\u00e9 nos corresponde como municipio para alcanzar el compromiso de saneamiento del Atoyac\u201d; afirma el edil.<\/p>\n<h3 data-start=\"968\" data-end=\"1152\"><strong>Rescate del r\u00edo Atoyac\u00a0<\/strong><\/h3>\n<p class=\"\" data-start=\"1154\" data-end=\"1391\">Concluye que el rescate del Atoyac no ser\u00e1 un esfuerzo de un solo d\u00eda; sino una tarea continua que requiere conciencia ciudadana; educaci\u00f3n ambiental y vigilancia permanente para evitar que el r\u00edo se utilice como un tiradero clandestino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente municipal de Coronango, Armando Aguirre Amaro, confirma que mantiene una estrecha relaci\u00f3n de trabajo con el coordinador del Plan H\u00eddrico de Puebla, Raymundo Atanacio Luna, con el objetivo de impulsar el rescate del R\u00edo Atoyac, uno de los afluentes m\u00e1s contaminados del estado. El alcalde detalla que Coronango fue uno de los primeros [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":455760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70357,8,9],"tags":[87692,1675,41,65,27,8254,18,1709],"yst_prominent_words":[30243,31024,30855,31826,29703,41350,29781,39733,41422,29713,31209,31016,30464],"class_list":["post-455759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronango","category-es-noticia","category-municipios","tag-armando-aguirre-amaro","tag-coronango","tag-es-noticia","tag-esnoticia","tag-hoyesnoticia","tag-hoyesnoticiaapp","tag-puebla","tag-rio-atoyac"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/455759"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=455759"}],"version-history":[{"count":3,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/455759\/revisions"}],"predecessor-version":[{"id":455798,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/455759\/revisions\/455798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media\/455760"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=455759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=455759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=455759"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=455759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}