{"id":46729,"date":"2017-06-15T17:55:31","date_gmt":"2017-06-15T23:55:31","guid":{"rendered":"https:\/\/www.sintesis.mx\/?p=46729"},"modified":"2017-06-15T17:55:31","modified_gmt":"2017-06-15T23:55:31","slug":"aspirantes-a-candidatos-de-morena-se-empoderan-con-el-resultado-en-el-edomex","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2017\/06\/15\/aspirantes-a-candidatos-de-morena-se-empoderan-con-el-resultado-en-el-edomex\/","title":{"rendered":"Aspirantes a candidatos de Morena se empoderan con el resultado en el EdoMex"},"content":{"rendered":"<p>La elecci\u00f3n celebrada el pasado 4 de junio en el<strong> Estado de M\u00e9xico<\/strong>, empoder\u00f3 a los militantes del Movimiento de Regeneraci\u00f3n Nacional (Morena), pues quienes aspiran a un cargo de elecci\u00f3n popular para el 2018, se ven reflejados en Delfina G\u00f3mez, reconoci\u00f3 el diputado federal, <strong>Rodrigo Abdala Dartigues<\/strong>.<\/p>\n<p>En entrevista, especific\u00f3 que independientemente de que puedan existir varios perfiles de candidatos por los diversos cargos de elecci\u00f3n, la realidad es que Morena se fortaleci\u00f3 y demostr\u00f3 que puede llegar a <strong>Los Pinos y Casa Puebla<\/strong>.<\/p>\n<p><em><strong>\u00abHay que ver el papel ejemplar de Delfina G\u00f3mez que gan\u00f3 la elecci\u00f3n en el Estado de M\u00e9xico, desgraciadamente no fue limpia, pero eso nos empoder\u00f3 como partido, sobre todo porque ahora representamos la segunda fuerza pol\u00edtica\u00bb, asever\u00f3.<\/strong><\/em><\/p>\n<p>En este sentido, precis\u00f3 que su partido inici\u00f3 el proceso para combatir \u00abla descarada alianza entre el <strong>Instituto Nacional Electoral<\/strong>, el PRI y el gobierno federal en donde Enrique Pe\u00f1a Nieto, movi\u00f3 toda la estructura para favorecer a su familiar Alfredo del Mazo\u00bb.<\/p>\n<p>En torno al anuncio del senador L<strong>uis Miguel Barbosa Huerta<\/strong>, de que emprendi\u00f3 el trabajo de operador pol\u00edtico en Puebla para difundir el proyecto de su l\u00edder nacional, Andr\u00e9s Manuel L\u00f3pez Obrador, <strong>Abdala Dartigues<\/strong>, aval\u00f3 la conformaci\u00f3n de estos comit\u00e9s de apoyo de cara al 2018.<\/p>\n<p>Asimismo, descart\u00f3 que estos recorridos de Miguel Barbosa sean actos de precampa\u00f1a, pues son acciones encaminadas a fortalecer a Andr\u00e9s Manuel L\u00f3pez Obrador, quien se perfila como la principal opci\u00f3n para el gobierno en el pa\u00eds.<\/p>\n<p>El diputado federal, reiter\u00f3 su deseo de buscar una candidatura, en ese sentido, advirti\u00f3 que no ha dejado de recorrer el estado, \u00abpor lo menos los fines de semana estamos puerta por puerta, hablando con la gente concientiz\u00e1ndolos de que la participaci\u00f3n es la mejor arma para cambiar este pa\u00eds\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En entrevista, especific\u00f3 que independientemente de que puedan existir varios perfiles de candidatos por los diversos cargos de elecci\u00f3n, la realidad es que Morena se fortaleci\u00f3 y demostr\u00f3 que puede llegar a Los Pinos y Casa Puebla.<\/p>\n","protected":false},"author":10,"featured_media":46758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[593,594,595,332,596],"yst_prominent_words":[],"class_list":["post-46729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-delfina-gomez","tag-estado-de-mexico","tag-luis-miguel-barbosa","tag-morena","tag-rodrigo-abdala-dartigues"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/46729"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=46729"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/46729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=46729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=46729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=46729"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=46729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}