{"id":482867,"date":"2026-01-30T12:40:14","date_gmt":"2026-01-30T18:40:14","guid":{"rendered":"https:\/\/sintesis.com.mx\/puebla\/?p=482867"},"modified":"2026-01-30T12:40:14","modified_gmt":"2026-01-30T18:40:14","slug":"habra-bodas-comunitarias","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2026\/01\/30\/habra-bodas-comunitarias\/","title":{"rendered":"Habr\u00e1 bodas comunitarias gratuitas en Cuautlancingo"},"content":{"rendered":"<p>En el marco del D\u00eda del Amor y la Amistad, el Gobierno municipal de Cuautlancingo, a trav\u00e9s del Registro Civil, llevar\u00e1 a cabo este<strong> 14 de febrero<\/strong> la <strong>celebraci\u00f3n de 50 bodas comunitarias gratuitas<\/strong> como parte del programa \u201cUnidos en Amor, celebrando en comunidad\u201d, que tiene el objetivo de brindar certeza jur\u00eddica y fortalecer la uni\u00f3n familiar en el municipio.<\/p>\n<p>La convocatoria se abri\u00f3 del 21 al 29 de enero de 2026, por <strong>lo que los lugares han sido cubiertos por 50 parejas<\/strong> que cumplieron con los criterios establecidos para participar en esta iniciativa dirigida a habitantes de Cuautlancingo.<\/p>\n<p>Cabe se\u00f1alar que esta iniciativa municipal tiene el aval de la Direcci\u00f3n General del Registro Civil del Estado de Puebla para el registro del matrimonio, la publicaci\u00f3n de actas preparatorias de presentaci\u00f3n matrimonial y la celebraci\u00f3n de matrimonios colectivos, incluyendo formas oficiales valoradas.<\/p>\n<p><strong>Este evento representa una acci\u00f3n de car\u00e1cter social que busca promover la legalidad<\/strong>, el bienestar familiar y el acceso a servicios esenciales, lo que reafirma el compromiso del Gobierno Municipal con el fortalecimiento del tejido social y la construcci\u00f3n de comunidades m\u00e1s s\u00f3lidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del D\u00eda del Amor y la Amistad, el Gobierno municipal de Cuautlancingo, a trav\u00e9s del Registro Civil, llevar\u00e1 a cabo este 14 de febrero la celebraci\u00f3n de 50 bodas comunitarias gratuitas como parte del programa \u201cUnidos en Amor, celebrando en comunidad\u201d, que tiene el objetivo de brindar certeza jur\u00eddica y fortalecer la [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":482868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[9624,45546,121,41,65,27,8254,28,18,23,8253,20668,40526],"yst_prominent_words":[34432,30823,38183,29906,30032,30034,29786,37415,31758,29816,32344,38216,30413],"class_list":["post-482867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipios","tag-14-de-febrero","tag-bodas","tag-cuautlancingo","tag-es-noticia","tag-esnoticia","tag-hoyesnoticia","tag-hoyesnoticiaapp","tag-municipios","tag-puebla","tag-slide","tag-slideapp","tag-slider","tag-sliderapp"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/482867"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=482867"}],"version-history":[{"count":1,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/482867\/revisions"}],"predecessor-version":[{"id":482869,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/482867\/revisions\/482869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media\/482868"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=482867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=482867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=482867"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=482867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}