{"id":78169,"date":"2017-12-05T16:54:57","date_gmt":"2017-12-05T22:54:57","guid":{"rendered":"http:\/\/sintesis.com.mx\/puebla\/?p=78169"},"modified":"2017-12-05T16:54:57","modified_gmt":"2017-12-05T22:54:57","slug":"detienen-a-conductor-que-mato-a-otro-en-el-barrio-de-la-luz","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/puebla\/2017\/12\/05\/detienen-a-conductor-que-mato-a-otro-en-el-barrio-de-la-luz\/","title":{"rendered":"Detienen a conductor que mat\u00f3 a otro en el barrio de \u00abLa Luz\u00bb"},"content":{"rendered":"<p>Mediante una orden de aprehensi\u00f3n fue detenido el conductor que dispar\u00f3 y caus\u00f3 la muerte de otro automovilista en el<a href=\"http:\/\/sintesis.com.mx\/puebla\/2017\/11\/21\/fallece-conductor-agredido-en-el-barrio-de-la-luz\/\"> barrio de La Luz<\/a> en noviembre pasado.<\/p>\n<p>Felipe \u00abN\u00bb fue detenido en las \u00faltimas horas y de acuerdo con la<a href=\"https:\/\/twitter.com\/FiscaliaPuebla?lang=es\"> <strong>Fiscal\u00eda General del Estado (FGE)<\/strong><\/a> en las pr\u00f3ximas horas se ampliar\u00e1 la informaci\u00f3n.<\/p>\n<p>Es preciso se\u00f1alar que el 18 de noviembre Daniel, de 25 a\u00f1os de edad, se baj\u00f3 de su auto Nissan Platina de color gris y se dirigi\u00f3 al conductor de un Volkswagen Jetta de color rojo.<\/p>\n<p>Cuando se presume le iba a reclamar alguna situaci\u00f3n, el ahora detenido le dispar\u00f3 y continu\u00f3 su marcha, as\u00ed que el acompa\u00f1ante del joven se baj\u00f3 y pidi\u00f3 ayuda al n\u00famero de emergencia.<\/p>\n<p>El conductor fue trasladado a un hospital donde falleci\u00f3 y fue d\u00edas despu\u00e9s que a trav\u00e9s de redes sociales se difundi\u00f3 un video de la agresi\u00f3n en calle Juan de Palafox y Mendoza y casi esquina 14 norte-sur.<\/p>\n<p>De acuerdo con los primeros reportes de ese d\u00eda, se presume que un altercado vial fue el detonante del reclamo y posterior homicidio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante una orden de aprehensi\u00f3n fue detenido el conductor que dispar\u00f3 y caus\u00f3 la muerte de otro automovilista en el barrio de La Luz en noviembre pasado.<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1285,3],"tags":[8122,7605,8121,688,23],"yst_prominent_words":[],"class_list":["post-78169","post","type-post","status-publish","format-standard","hentry","category-justicia","category-puebla","tag-altercado-vial","tag-barrio-de-la-luz","tag-homicidio-conductor","tag-juan-de-palafox-y-mendoza","tag-slide"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/78169"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/comments?post=78169"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts\/78169\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/media?parent=78169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/categories?post=78169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags?post=78169"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/yst_prominent_words?post=78169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}