{"id":19193,"count":32,"description":"","link":"https:\/\/sintesis.com.mx\/puebla\/tag\/calle-5-de-mayo\/","name":"calle 5 de mayo","slug":"calle-5-de-mayo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags\/19193"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sintesis.com.mx\/puebla\/wp-json\/wp\/v2\/posts?tags=19193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}