{"id":119474,"date":"2021-01-30T17:18:53","date_gmt":"2021-01-30T23:18:53","guid":{"rendered":"https:\/\/sintesis.com.mx\/tlaxcala\/?p=119474"},"modified":"2021-01-30T17:20:27","modified_gmt":"2021-01-30T23:20:27","slug":"ejecutaran-programa-mejoramiento","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/tlaxcala\/2021\/01\/30\/ejecutaran-programa-mejoramiento\/","title":{"rendered":"Ejecutar\u00e1n Programa de Mejoramiento Urbano en la ciudad capital"},"content":{"rendered":"<p>La <strong>Presidencia Municipal de <a href=\"https:\/\/sintesis.com.mx\/tlaxcala\/2021\/01\/21\/mildred-vergara-vicepresidenta-conamm\/\">Tlaxcala<\/a><\/strong> en coordinaci\u00f3n con la <strong>Secretar\u00eda de Desarrollo Agrario, Territorial y Urbano (SEDATU)<\/strong>, <strong>ejecutar\u00e1n<\/strong> cuatro grandes proyectos en la ciudad capital a trav\u00e9s del <strong>Programa de Mejoramiento Urbano<\/strong>, los cuales traer\u00e1n beneficios a los tlaxcaltecas.<\/p>\n<p>Durante un recorrido por los espacios p\u00fablicos que ser\u00e1n rehabilitados, la alcaldesa, <a href=\"https:\/\/twitter.com\/milivergaraz\"><strong>Mildred Vergara Zavala,<\/strong> <\/a>reiter\u00f3 que el Ayuntamiento de Tlaxcala colaborar\u00e1 en todas las acciones necesarias para el buen desarrollo de los proyectos, pues el objetivo es mejorar la calidad de vida, los servicios y la infraestructura de la capital.<\/p>\n<p>Durante un recorrido por los espacios p\u00fablicos que ser\u00e1n rehabilitados, la alcaldesa, Mildred Vergara Zavala reiter\u00f3 que el Ayuntamiento de Tlaxcala colaborar\u00e1 en todas las acciones necesarias para el buen desarrollo de los proyectos, pues el objetivo es mejorar la calidad de vida, los servicios y la infraestructura de la capital.<\/p>\n<p>En tanto, el titular de la SEDATU, Rom\u00e1n Guillermo Meyer Falc\u00f3n manifest\u00f3 que dicho programa tiene como prop\u00f3sito generar condiciones que fomenten la mejora en la vida de comunidades, con la rehabilitaci\u00f3n de espacios p\u00fablicos.<\/p>\n<p>Detall\u00f3 que dentro del Plan de Acci\u00f3n se contemplan cuatro importantes proyectos que son: Renovaci\u00f3n de la Plaza \u00abXicoht\u00e9ncatl\u00bb, Construcci\u00f3n del Mercado de Artesanos, Renovaci\u00f3n de la Plaza de la Constituci\u00f3n y Construcci\u00f3n del Mercado Municipal \u201cEmilio S\u00e1nchez Piedras\u201d.<\/p>\n<p>De esta forma la alcald\u00eda de Tlaxcala suma esfuerzos con el Gobierno Federal para impulsar el desarrollo del municipio y brindar a la ciudadan\u00eda una mejor ciudad, adem\u00e1s de espacios dignos para un crecimiento econ\u00f3mico de sus habitantes.<\/p>\n<p>Durante el recorrido tambi\u00e9n estuvieron presentes el Secretario del Ayuntamiento, V\u00edctor Hugo Guti\u00e9rrez Morales; el Director de Obras P\u00fablicas y Desarrollo Urbano, Miguel \u00c1ngel Trejo Mendoza, adem\u00e1s de funcionarios de la SEDATU.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Presidencia Municipal de Tlaxcala en coordinaci\u00f3n con la Secretar\u00eda de Desarrollo Agrario, Territorial y Urbano (SEDATU), ejecutar\u00e1n cuatro grandes proyectos en la ciudad capital a trav\u00e9s del Programa de Mejoramiento Urbano, los cuales traer\u00e1n beneficios a los tlaxcaltecas. Durante un recorrido por los espacios p\u00fablicos que ser\u00e1n rehabilitados, la alcaldesa, Mildred Vergara Zavala, reiter\u00f3 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[1218,965,50129,3154,1387,352,3326,153,50130],"yst_prominent_words":[7963,47217,31620],"class_list":["post-119474","post","type-post","status-publish","format-standard","hentry","category-metropoli-tlaxcala","tag-capital","tag-ciudad","tag-ejecutaran","tag-mejoramiento","tag-programa","tag-slide","tag-slideapp","tag-tlaxcala","tag-urbano"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/119474"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/comments?post=119474"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/119474\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media?parent=119474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/categories?post=119474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/tags?post=119474"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/yst_prominent_words?post=119474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}