{"id":152187,"date":"2021-12-21T15:48:48","date_gmt":"2021-12-21T21:48:48","guid":{"rendered":"https:\/\/sintesis.com.mx\/tlaxcala\/?p=152187"},"modified":"2021-12-21T16:02:41","modified_gmt":"2021-12-21T22:02:41","slug":"rinden-protesta-cuatro-jueces","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/tlaxcala\/2021\/12\/21\/rinden-protesta-cuatro-jueces\/","title":{"rendered":"Rinden protesta cuatro jueces municipales ante el TSJE"},"content":{"rendered":"<p>En sesi\u00f3n ordinaria de Pleno, el magistrado presidente del <strong>Tribunal Superior de Justicia y del Consejo de la Judicatura del Estado (TSJ-CJE)<\/strong>,<a href=\"https:\/\/sintesis.com.mx\/tlaxcala\/?s=H%C3%A9ctor+Maldonado+Bonilla%2C\"><strong> H\u00e9ctor Maldonado Bonilla<\/strong>,<\/a> tom\u00f3 protesta a cuatro personas que cumplieron con los requisitos para el cargo de <strong>Juez Municipal<\/strong>, de mismo n\u00famero de Ayuntamientos.<\/p>\n<p>Lo anterior, con fundamento en lo dispuesto por los art\u00edculos <strong>154 y 155 de la Ley Municipal del Estado<\/strong>, y 2Bis Fracci\u00f3n X, de la <strong>Ley Org\u00e1nica del Poder Judicial de Tlaxcala<\/strong>.<\/p>\n<p>Los abogados que cumplieron con los requisitos establecidos en la norma, fueron los integrantes de los Ayuntamientos de Santa Isabel Tetlatlahuca, Tenancingo, Xaltocan y San Francisco Tetlanohcan.<\/p>\n<p>Se trata de <strong>Sergio Moreno Desanpedro<\/strong>,<strong> No\u00e9 Hern\u00e1ndez Su\u00e1rez<\/strong>,<strong> Karen Anah\u00ed<\/strong> <strong>Cordero Galind<\/strong>o y <strong>Teresa Mendieta Zamora<\/strong>, respectivamente.<\/p>\n<p>De esta manera, ya son 24 las juezas y los jueces municipales que cumplieron con los requisitos de Ley, y rindieron protesta ante el Pleno del <strong>TSJ.<\/strong><\/p>\n<p>Los requisitos que marca la norma para recibir el nombramiento, consisten en presentar t\u00edtulo y cedula profesional, as\u00ed como la copia certificada del acta de Cabildo, en la que fueron designados como <a href=\"https:\/\/sintesis.com.mx\/tlaxcala\/?s=Juez+Municipal.\"><strong>Juez Municipal.<\/strong><\/a><\/p>\n<p>Adem\u00e1s, Carta de No Antecedentes Penales, de No<strong> Recomendaci\u00f3n emitida por la <a href=\"https:\/\/www.cndh.org.mx\/palabras-clave\/3509\/cedh\">Comisi\u00f3n Estatal de Derechos Humanos (CEDH)<\/a><\/strong>, de No Inhabilitado, as\u00ed como constancia de radicaci\u00f3n y acta de nacimiento.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-152190\" src=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2021\/12\/FB_IMG_1640120960971.jpg\" alt=\"\" width=\"720\" height=\"480\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En sesi\u00f3n ordinaria de Pleno, el magistrado presidente del Tribunal Superior de Justicia y del Consejo de la Judicatura del Estado (TSJ-CJE), H\u00e9ctor Maldonado Bonilla, tom\u00f3 protesta a cuatro personas que cumplieron con los requisitos para el cargo de Juez Municipal, de mismo n\u00famero de Ayuntamientos. Lo anterior, con fundamento en lo dispuesto por los [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53904,150],"tags":[154,18601,19446],"yst_prominent_words":[44387,7638,25999,11260,7519,7961,11029,7531,11509,20922],"class_list":["post-152187","post","type-post","status-publish","format-standard","hentry","category-judicial","category-metropoli-tlaxcala","tag-tlaxesnoticia","tag-tlaxhoyesnoticia","tag-tlaxhoyesnoticiaapp"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/152187"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/comments?post=152187"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/152187\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media?parent=152187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/categories?post=152187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/tags?post=152187"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/yst_prominent_words?post=152187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}