{"id":232626,"date":"2023-08-29T14:57:33","date_gmt":"2023-08-29T20:57:33","guid":{"rendered":"https:\/\/sintesis.com.mx\/tlaxcala\/?p=232626"},"modified":"2023-08-29T14:58:47","modified_gmt":"2023-08-29T20:58:47","slug":"cortes-entrega-mochilas","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/tlaxcala\/2023\/08\/29\/cortes-entrega-mochilas\/","title":{"rendered":"Nancy Cort\u00e9s entrega mochilas escolares a ni\u00f1os y ni\u00f1as de preescolar y primaria en Amaxac"},"content":{"rendered":"<p class=\"p1\">La presidenta de Amaxac de Guerrero, Nancy Cort\u00e9s V\u00e1zquez encabez\u00f3 el arranque de la entrega de mochilas gratuitas, que otorgar\u00e1 el ayuntamiento en beneficio de <strong>m\u00e1s de mil alumnos de nivel preescolar y primaria del municipio y sus comunidades<\/strong>.<\/p>\n<p class=\"p2\"><span class=\"s2\">Desde la explanada del parque municipal, se inici\u00f3 con el arranque formal en donde la alcaldesa acompa\u00f1ada de regidores as\u00ed como ni\u00f1as y ni\u00f1os alumnos de escuelas de la demarcaci\u00f3n con directores, alumnos y padres de familias, hizo entrega simb\u00f3lica de mochilas escolares a los que peque\u00f1os beneficiados.<\/span><\/p>\n<p class=\"p2\"><span class=\"s2\">En el segundo d\u00eda del inicio de clases, Cortes V\u00e1zquez afirm\u00f3 que con la entrega de este art\u00edculo escolar se busca contribuir en el ahorro familiar y seguir\u00e1 siendo un aliado de la educaci\u00f3n, contribuyendo con acciones y atendiendo las solicitudes de la comunidad escolar.<\/span><\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a0495510e7a1  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0495510e7a1  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0495510e7a1  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0495510e7a1  .td-doubleSlider-2 .td-item4 {\r\n                        background: url(https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0495510e7a1  .td-doubleSlider-2 .td-item5 {\r\n                        background: url(https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a0495510e7a1  .td-doubleSlider-2 .td-item6 {\r\n                        background: url(https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193-80x60.jpeg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a0495510e7a1\" class=\"td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> of 6<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-scaled.jpeg\" title=\"IMG_6226\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-747x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-747x420.jpeg 747w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-300x169.jpeg 300w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-1024x576.jpeg 1024w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-768x432.jpeg 768w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-1536x864.jpeg 1536w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-2048x1152.jpeg 2048w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-696x392.jpeg 696w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6226-1068x601.jpeg 1068w\" sizes=\"(max-width: 747px) 100vw, 747px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-scaled.jpeg\" title=\"IMG_6229\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-747x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-747x420.jpeg 747w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-300x169.jpeg 300w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-1024x576.jpeg 1024w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-768x432.jpeg 768w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-1536x864.jpeg 1536w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-2048x1152.jpeg 2048w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-696x392.jpeg 696w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6229-1068x601.jpeg 1068w\" sizes=\"(max-width: 747px) 100vw, 747px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-scaled.jpeg\" title=\"IMG_6231\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-747x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-747x420.jpeg 747w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-300x169.jpeg 300w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-1024x576.jpeg 1024w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-768x432.jpeg 768w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-1536x864.jpeg 1536w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-2048x1152.jpeg 2048w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-696x392.jpeg 696w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6231-1068x601.jpeg 1068w\" sizes=\"(max-width: 747px) 100vw, 747px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item4\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183.jpeg\" title=\"IMG_6183\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183-630x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183-630x420.jpeg 630w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183-300x200.jpeg 300w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183-1024x683.jpeg 1024w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183-768x512.jpeg 768w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183-1536x1024.jpeg 1536w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183-696x464.jpeg 696w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183-1068x712.jpeg 1068w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6183.jpeg 1920w\" sizes=\"(max-width: 630px) 100vw, 630px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item5\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189.jpeg\" title=\"IMG_6189\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189-630x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189-630x420.jpeg 630w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189-300x200.jpeg 300w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189-1024x683.jpeg 1024w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189-768x512.jpeg 768w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189-1536x1024.jpeg 1536w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189-696x464.jpeg 696w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189-1068x712.jpeg 1068w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6189.jpeg 1920w\" sizes=\"(max-width: 630px) 100vw, 630px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item6\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193.jpeg\" title=\"IMG_6193\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193-630x420.jpeg\" srcset=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193-630x420.jpeg 630w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193-300x200.jpeg 300w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193-1024x683.jpeg 1024w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193-768x512.jpeg 768w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193-1536x1024.jpeg 1536w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193-696x464.jpeg 696w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193-1068x712.jpeg 1068w, https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2023\/08\/IMG_6193.jpeg 1920w\" sizes=\"(max-width: 630px) 100vw, 630px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item4\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item5\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item6\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n","protected":false},"excerpt":{"rendered":"<p>La presidenta de Amaxac de Guerrero, Nancy Cort\u00e9s V\u00e1zquez encabez\u00f3 el arranque de la entrega de mochilas gratuitas, que otorgar\u00e1 el ayuntamiento en beneficio de m\u00e1s de mil alumnos de nivel preescolar y primaria del municipio y sus comunidades. Desde la explanada del parque municipal, se inici\u00f3 con el arranque formal en donde la alcaldesa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":232630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59297,1751,52854,150],"tags":[352,154,5073,5697],"yst_prominent_words":[7652,31315,8337,7688,18448,10391],"class_list":["post-232626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amaxac","category-amaxac-de-guerrero","category-educacion","category-metropoli-tlaxcala","tag-slide","tag-tlaxesnoticia","tag-tlaxesnoticiaapp","tag-tlaxslideapp"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/232626"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/comments?post=232626"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/232626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media\/232630"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media?parent=232626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/categories?post=232626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/tags?post=232626"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/yst_prominent_words?post=232626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}