{"id":259104,"date":"2024-06-10T18:29:43","date_gmt":"2024-06-11T00:29:43","guid":{"rendered":"https:\/\/sintesis.com.mx\/tlaxcala\/?p=259104"},"modified":"2024-06-10T18:29:43","modified_gmt":"2024-06-11T00:29:43","slug":"gran-festival-taurino","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/tlaxcala\/2024\/06\/10\/gran-festival-taurino\/","title":{"rendered":"Gran Festival Taurino en apoyo del matador Jos\u00e9 Alberto Ortega"},"content":{"rendered":"<ul>\n<li>\n<h3><em><strong>Festival ben\u00e9fico con el objetivo de recaudar fondos para la atenci\u00f3n m\u00e9dica del matador<\/strong><\/em><\/h3>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Este pr\u00f3ximo 16 de junio se realizar\u00e1 el Gran Festival Taurino en la Monumental Plaza de Toros Rodolfo Rodr\u00edguez \u00abEl Pana\u00bb a partir de las 4:30 de la tarde con el objetivo de recaudar fondos para la atenci\u00f3n m\u00e9dica del matador Jos\u00e9 Alberto Ortega.<\/p>\n<p>El director del Instituto Tlaxcalteca Taurino, Jos\u00e9 Luis Angelino, resalt\u00f3 la importancia de la uni\u00f3n dentro de la comunidad taurina, as\u00ed como el agradecimiento a las diversas ganader\u00edas que se sumaron con la donaci\u00f3n de un novillo para dicho festejo.<\/p>\n<p>Para ello, quienes acudieron a la rueda de prensa dieron a conocer el cartel que estar\u00e1 conformado por toreros de tres generaciones; Jos\u00e9 Luis Angelino; Jos\u00e9 Mauricio; Arturo Sald\u00edvar; Ferm\u00edn Rivera; Juan Luis Silis; H\u00e9ctor Gabriel y Sebasti\u00e1n Palomo.<\/p>\n<p>Tras la fuerte cornada que recibi\u00f3 el matador Jos\u00e9 Alberto Ortega en febrero, este festival pretende reunir la mayor cantidad econ\u00f3mica posible con el fin de continuar con la atenci\u00f3n del joven matador.<\/p>\n<p>Po su parte Juan Luis Silis exhort\u00f3 a la ciudadan\u00eda a que puedan asistir a este festival y sobre todo a la comunidad Taurina a mantenerse solidaria ante lo sucedido para que el matador pueda recuperarse en su totalidad.<\/p>\n<p>Los boletos salieron a la venta desde el d\u00eda nueve de junio y se pueden adquirir en el restaurante La Escondida en Apizaco as\u00ed como el d\u00eda del evento en la taquilla de la plaza de toros; los costos ser\u00e1n de 150 pesos en zona general y 250 en sombra.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Festival ben\u00e9fico con el objetivo de recaudar fondos para la atenci\u00f3n m\u00e9dica del matador &nbsp; Este pr\u00f3ximo 16 de junio se realizar\u00e1 el Gran Festival Taurino en la Monumental Plaza de Toros Rodolfo Rodr\u00edguez \u00abEl Pana\u00bb a partir de las 4:30 de la tarde con el objetivo de recaudar fondos para la atenci\u00f3n m\u00e9dica del [&hellip;]<\/p>\n","protected":false},"author":88,"featured_media":259105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[61111,61110,61112,52534],"yst_prominent_words":[8270,10965,8275,8269,9284,9269,9285,18328,8272],"class_list":["post-259104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metropoli-tlaxcala","tag-gran-festival-taurino","tag-matador-jose-alberto-ortega","tag-monumental-plaza-de-toros-rodolfo-rodriguez-el-pana","tag-recaudacion-de-fondos"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/259104"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/comments?post=259104"}],"version-history":[{"count":1,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/259104\/revisions"}],"predecessor-version":[{"id":259153,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/259104\/revisions\/259153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media\/259105"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media?parent=259104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/categories?post=259104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/tags?post=259104"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/yst_prominent_words?post=259104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}