{"id":296485,"date":"2025-08-16T10:21:00","date_gmt":"2025-08-16T16:21:00","guid":{"rendered":"https:\/\/sintesis.com.mx\/tlaxcala\/?p=296485"},"modified":"2025-08-16T10:21:00","modified_gmt":"2025-08-16T16:21:00","slug":"spotify-presenta-dj-inteligencia-artificial","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/tlaxcala\/2025\/08\/16\/spotify-presenta-dj-inteligencia-artificial\/","title":{"rendered":"Spotify presenta su DJ con inteligencia artificial"},"content":{"rendered":"<p class=\"p2\"><em><strong>M\u00fasica personalizada que viaja a trav\u00e9s del tiempo<\/strong><\/em><\/p>\n<p class=\"p2\">Spotify<span class=\"s1\"> ha dado un paso m\u00e1s en la personalizaci\u00f3n de la experiencia musical con el lanzamiento de su DJ impulsado por inteligencia artificial, una funci\u00f3n exclusiva para usuarios Premium que combina la tecnolog\u00eda de recomendaci\u00f3n con una voz realista que gu\u00eda al oyente en cada sesi\u00f3n.<\/span><\/p>\n<p class=\"p2\"><span class=\"s1\">El prop\u00f3sito de esta herramienta es ofrecer un recorrido sonoro hecho a la medida de cada persona. Para lograrlo, el DJ utiliza los datos de escucha acumulados a lo largo del tiempo: desde las canciones que m\u00e1s sonaron en los \u00faltimos meses hasta los artistas favoritos de a\u00f1os anteriores. De esta manera, no solo propone m\u00fasica nueva, sino que tambi\u00e9n lleva al usuario en un viaje nost\u00e1lgico a trav\u00e9s de remixes y redescubrimientos de su propio historial musical.<\/span><\/p>\n<p class=\"p2\"><span class=\"s1\">El funcionamiento de esta innovaci\u00f3n se sostiene en tres pilares: la tecnolog\u00eda de recomendaciones de Spotify, que identifica los g\u00e9neros y artistas preferidos de cada perfil; la participaci\u00f3n de editores musicales, quienes a\u00f1aden contexto cultural e hist\u00f3rico a los temas seleccionados; y la voz generada a partir de la plataforma Sonantic, que hace que la experiencia se sienta tan cercana como escuchar a un DJ real. La primera voz elegida fue la del neoyorquino Xavier \u201cX\u201d Jernigan, que aporta cercan\u00eda y un estilo narrativo propio.<\/span><\/p>\n<p class=\"p2\"><span class=\"s1\">A partir de 2025, la funci\u00f3n tambi\u00e9n incorpora comandos de voz, lo que permite a los usuarios pedir m\u00fasica seg\u00fan su estado de \u00e1nimo, una actividad espec\u00edfica, un g\u00e9nero o un artista en particular, reforzando as\u00ed el car\u00e1cter interactivo de esta experiencia.<\/span><\/p>\n<p class=\"p2\"><span class=\"s1\">La recepci\u00f3n ha sido diversa: mientras miles de oyentes destacan la capacidad del DJ para descubrir m\u00fasica nueva y recordar canciones olvidadas, otros se\u00f1alan que a\u00fan est\u00e1 lejos de reproducir la espontaneidad de un DJ humano. Sin embargo, este desarrollo confirma la apuesta de Spotify por fusionar algoritmos con inteligencia artificial generativa para llevar la personalizaci\u00f3n musical a un nivel sin precedentes.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fasica personalizada que viaja a trav\u00e9s del tiempo Spotify ha dado un paso m\u00e1s en la personalizaci\u00f3n de la experiencia musical con el lanzamiento de su DJ impulsado por inteligencia artificial, una funci\u00f3n exclusiva para usuarios Premium que combina la tecnolog\u00eda de recomendaci\u00f3n con una voz realista que gu\u00eda al oyente en cada sesi\u00f3n. El [&hellip;]<\/p>\n","protected":false},"author":89,"featured_media":296486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52854,150],"tags":[60153,62052,607,153,154,5073,19446,157,5697],"yst_prominent_words":[35107,13556,8100,12618,7780,8975,31183,9790,9438,8220,9254,7784,8044,8412,24212],"class_list":["post-296485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion-tecnologia","category-metropoli-tlaxcala","tag-inteligencia-artificial","tag-spotify","tag-tecnologia","tag-tlaxcala","tag-tlaxesnoticia","tag-tlaxesnoticiaapp","tag-tlaxhoyesnoticiaapp","tag-tlaxslide","tag-tlaxslideapp"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/296485"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/comments?post=296485"}],"version-history":[{"count":1,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/296485\/revisions"}],"predecessor-version":[{"id":296487,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/296485\/revisions\/296487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media\/296486"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media?parent=296485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/categories?post=296485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/tags?post=296485"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/yst_prominent_words?post=296485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}