{"id":41249,"date":"2017-06-02T14:35:32","date_gmt":"2017-06-02T20:35:32","guid":{"rendered":"https:\/\/www.sintesis.mx\/?p=41249"},"modified":"2017-06-02T14:35:32","modified_gmt":"2017-06-02T20:35:32","slug":"aumentan-padecimientos-alimenticios-en-tlaxcala","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/tlaxcala\/2017\/06\/02\/aumentan-padecimientos-alimenticios-en-tlaxcala\/","title":{"rendered":"Aumentan padecimientos alimenticios en  Tlaxcala"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>De acuerdo al bolet\u00edn epidemiol\u00f3gico de la<strong> Secretar\u00eda de Salud nacional<\/strong>, el estado de <strong>Tlaxcala<\/strong> registra a la fecha un total de dos <strong>mil 150 casos de diferentes problemas de salud alimenticia.<\/strong><\/p>\n<p>Entre los padecimientos que se observan en el balance, destacan los siguientes: <strong>desnutrici\u00f3n severa, moderada, y leve, obesidad, anorexia, bulimia y otros trastornos alimentarios<\/strong>.<\/p>\n<p>De estos, los que registran la mayor cantidad de casos en todo el estado son los de obesidad con mil 833 pacientes detectados. La cantidad de casos que se contabilizan tan solo para este padecimiento, casi alcanzan los que se registraron en todo el 2016, cuando la incidencia fue de mil 887 casos.<\/p>\n<p>Despu\u00e9s siguen los casos de desnutrici\u00f3n leve con 286 casos, en contraste con los 300 acumulados en todo el ejercicio anterior.<\/p>\n<p>En tanto que los que menor cantidad registran son los de desnutrici\u00f3n severa con \u00fanicamente cinco casos en lo que va del a\u00f1o, contra los 16 del a\u00f1o anterior. Por desnutrici\u00f3n moderada, suman 15 casos en 2017, contra los 41 del ejercicio 2016.<\/p>\n<p>En lo que respecta a padecimientos como anorexia, bulimia y otros trastornos alimenticios, Tlaxcala tiene once casos, contra s\u00f3lo uno en el periodo anterior.<\/p>\n<p>El corte que ofreci\u00f3 la Secretar\u00eda de Salud del gobierno de la Rep\u00fablica corresponde a la semana epidemiol\u00f3gica n\u00famero 20, que transcurri\u00f3 del 14 al 20 de mayo pasado.<\/p>\n<p>En otra categor\u00eda de los padecimientos que observa peri\u00f3dicamente la Secretar\u00eda de Salud, destacan los relacionados con el alcoholismo.<\/p>\n<p>De estos, sobresale para Tlaxcala la intoxicaci\u00f3n aguda por alcohol con un total de 139 casos; tambi\u00e9n se ubica la enfermedad alcoh\u00f3lica del h\u00edgado con 25 incidencias; y la cirrosis hep\u00e1tica alcoh\u00f3lica con diez casos.    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los que registran la mayor cantidad de casos en todo el estado son los de obesidad con mil 833 pacientes detectados<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[235,236,237,153,154,157],"yst_prominent_words":[],"class_list":["post-41249","post","type-post","status-publish","format-standard","hentry","category-metropoli-tlaxcala","tag-comida","tag-obesidad","tag-padecimientos-alimenticios","tag-tlaxcala","tag-tlaxesnoticia","tag-tlaxslide"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/41249"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/comments?post=41249"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/41249\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media?parent=41249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/categories?post=41249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/tags?post=41249"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/yst_prominent_words?post=41249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}