{"id":69233,"date":"2018-05-06T15:09:16","date_gmt":"2018-05-06T20:09:16","guid":{"rendered":"http:\/\/sintesis.com.mx\/tlaxcala\/?p=69233"},"modified":"2018-05-06T16:39:47","modified_gmt":"2018-05-06T21:39:47","slug":"alvarez-temor-guerra-sucia","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/tlaxcala\/2018\/05\/06\/alvarez-temor-guerra-sucia\/","title":{"rendered":"\u00c1lvarez Lima sin temor a \u201cguerra sucia\u201d"},"content":{"rendered":"<p>El <strong>candidato al Senado de la Rep\u00fablica por Tlaxcala<\/strong> del partido por el Movimiento de Regeneraci\u00f3n Nacional (Morena), <strong>Jos\u00e9 Antonio \u00c1lvarez Lima<\/strong> consider\u00f3 que la <a href=\"https:\/\/twitter.com\/TlaxSintesis\/status\/942845188694687744\">\u201cguerra sucia\u201d<\/a> es inevitable en los procesos de campa\u00f1a, por lo que dijo <strong>no tener miedo a ella, por lo que conf\u00eda en el criterio de los ciudadanos.<\/strong><\/p>\n<p>En una entrevista, el ex mandatario estatal <strong>pidi\u00f3 a los <a href=\"http:\/\/sintesis.com.mx\/tlaxcala\/\">tlaxcaltecas<\/a> exigir pruebas contundentes a los dichos de algunas personas o medios de comunicaci\u00f3n que descalifiquen a alguno de los candidatos a contender este 1 de julio.<\/strong><\/p>\n<p>\u201c<strong><em>La guerra sucia es inevitable de la democracia, y nosotros los pol\u00edticos tenemos que respetar el criterio de los ciudadanos, entonces si alguien me acusa de haber violado los derechos humanos de alguien lo tiene que demostrar, y si no presentan alguna prueba ojal\u00e1 que el criterio de las personas sea el suficiente para decir, lo acusan de algo pero no lo prueban<\/em><\/strong>\u201d, consider\u00f3.<\/p>\n<p>Refiri\u00f3 que hoy en d\u00eda, <strong>los ciudadanos cuentan con un alto criterio para saber distinguir entre lo que son calumnias y lo que es verdad<\/strong>, aunque reconoci\u00f3 que en la actualidad es muy f\u00e1cil acusar de manera p\u00fablica a alguien sin prueba alguna.<\/p>\n<p>\u201c<strong><em>Con las redes sociales ahora, en mi parecer, pues son una ventaja ciudadana, y pues ah\u00ed hay de todo, hay verdades, cosas que son irrelevantes y son los ciudadanos que tienen que tener el criterio, tenemos que confiar en la madures de las personas o ir creando esa madurez, as\u00ed que no le temo a la guerra sucia<\/em><\/strong>\u201d, insisti\u00f3.<\/p>\n<p>Por otro lado, a m\u00e1s de un mes de que inici\u00f3 su campa\u00f1a electoral en busca de un lugar en la C\u00e1mara Alta del Congreso de la Uni\u00f3n, <strong>explic\u00f3 que como miembro del movimiento nacional de que encabeza Andr\u00e9s Manuel L\u00f3pez Obrador, a \u00e9l le correspondi\u00f3 el trabajo de toque de puertas en la parte norte y oriente de Tlaxcala.<\/strong><\/p>\n<p>\u201c<strong><em>Nosotros tenemos una estrategia nacional, nosotros somos parte de un movimiento que encabeza Andr\u00e9s Manuel L\u00f3pez Obrador, y entonces no tenemos digamos propuestas de car\u00e1cter individual, nosotros como parte de ese movimiento, porque estamos convencidos de la filosof\u00eda de Morena, las propuestas que propone para hacer el cambio verdadero\u2026por lo que no tenemos duda de que vamos a gana<\/em><\/strong>r\u201d, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diputado Jos\u00e9 Antonio \u00c1lvarez Lima consider\u00f3 que la \u201cguerra sucia\u201d es inevitable en los procesos de campa\u00f1a por lo que no le teme a ella <\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[303,36,4290,153,157],"yst_prominent_words":[],"class_list":["post-69233","post","type-post","status-publish","format-standard","hentry","category-metropoli-tlaxcala","tag-campana","tag-elecciones","tag-jose-antonio-alvarez-lima","tag-tlaxcala","tag-tlaxslide"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/69233"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/comments?post=69233"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/69233\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media?parent=69233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/categories?post=69233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/tags?post=69233"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/yst_prominent_words?post=69233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}