{"id":93802,"date":"2019-11-06T17:14:08","date_gmt":"2019-11-06T23:14:08","guid":{"rendered":"https:\/\/sintesis.com.mx\/tlaxcala\/?p=93802"},"modified":"2019-11-06T17:14:08","modified_gmt":"2019-11-06T23:14:08","slug":"presenta-sepe-libros-geografia-primaria-nueva-generacion","status":"publish","type":"post","link":"https:\/\/sintesis.com.mx\/tlaxcala\/2019\/11\/06\/presenta-sepe-libros-geografia-primaria-nueva-generacion\/","title":{"rendered":"Presenta SEPE libros de geograf\u00eda de primaria de nueva generaci\u00f3n"},"content":{"rendered":"<p class=\"yiv0105323583MsoNormal\">El<strong> Secretario de Educaci\u00f3n P\u00fablica del Estado<\/strong> y Director General de la Unidad de Servicios Educativos de Tlaxcala, <strong>Florentino Dom\u00ednguez Ord\u00f3\u00f1ez<\/strong>, encabez\u00f3 la presentaci\u00f3n del <strong>libro<\/strong> de <strong>geograf\u00eda<\/strong> de <strong>sexto<\/strong> grado de <strong>primaria<\/strong>, donde destac\u00f3 que el texto es el primero de una nueva generaci\u00f3n de libros.<\/p>\n<p class=\"yiv0105323583MsoNormal\">En este sentido, se\u00f1al\u00f3 que el ejemplar cuenta con pasta dura que lo hace m\u00e1s resistente y acorde con la era digital tiene un <strong>c\u00f3digo QR<\/strong> que al escanearlo &#8211;<em><strong>con el apoyo de tabletas o tel\u00e9fonos inteligentes<\/strong><\/em>-, brinda acceso a contenido multimedia para hacer m\u00e1s atractivo el proceso de <strong>aprendizaje<\/strong>.<\/p>\n<p class=\"yiv0105323583MsoNormal\">Florentino Dom\u00ednguez detall\u00f3 que en Tlaxcala un total de <strong>26 mil 660 alumnos<\/strong> de sexto grado ya cuentan con este nuevo material que destaca por ser un texto multianual, que al finalizar el ciclo escolar ser\u00e1 resguardado por las escuelas para que tenga un periodo de utilidad de hasta cuatro generaciones.<\/p>\n<p class=\"yiv0105323583MsoNormal\">El titular de la SEPE explic\u00f3 que el libro es acompa\u00f1ado de un cuadernillo de actividades para que los alumnos hagan anotaciones y den seguimiento a sus tareas escolares.<\/p>\n<p class=\"yiv0105323583MsoNormal\" style=\"text-align: center;\"><em><strong>\u201cEsta nueva generaci\u00f3n de libros permite acercarnos a otras fuentes de informaci\u00f3n y formatos, como videos, presentaciones multimedia y p\u00e1ginas de Internet. Con esta herramienta los alumnos y maestros tendr\u00e1n acceso a contenidos de National Geographic, la ONU, el Inegi y la UNAM\u201d<\/strong><\/em>, se\u00f1al\u00f3.<\/p>\n<p class=\"yiv0105323583MsoNormal\">A la presentaci\u00f3n del libro asistieron alumnos, docentes y padres de familia, quienes conocieron esta nueva herramienta y sus contenidos, que contribuir\u00e1n a un mejor aprendizaje.<\/p>\n<p class=\"yiv0105323583MsoNormal\">En su oportunidad, <strong>Israel Ronquillo S\u00e1nchez<\/strong>, Coordinador Estatal de Libros de Texto Gratuitos, explic\u00f3 que en Tlaxcala se entregaron <strong>un mill\u00f3n 194 mil 601 ejemplares<\/strong> en nivel primaria, de los cuales <strong>26 mil 660 son de geograf\u00eda de sexto grado.<\/strong><\/p>\n<p class=\"yiv0105323583MsoNormal\">Cabe se\u00f1alar que la Comisi\u00f3n Nacional de Libros de Texto Gratuitos contempla un periodo de utilidad del ejemplar de cinco ciclos escolares, con lo que se contribuir\u00e1 a ahorrar cuatro mil 568 toneladas de papel, evitar la tala de 40 mil \u00e1rboles, as\u00ed como la emisi\u00f3n de 10 mil toneladas de di\u00f3xido de carbono y el gasto de 600 millones de litros de agua.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-93803 size-large\" src=\"https:\/\/sintesis.com.mx\/tlaxcala\/wp-content\/uploads\/2019\/11\/sepe-17-1024x706.jpeg\" alt=\"Presenta SEPE libros de geograf\u00eda de primaria de nueva generaci\u00f3n\" width=\"640\" height=\"441\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Secretario de Educaci\u00f3n P\u00fablica del Estado y Director General de la Unidad de Servicios Educativos de Tlaxcala, Florentino Dom\u00ednguez Ord\u00f3\u00f1ez, encabez\u00f3 la presentaci\u00f3n del libro de geograf\u00eda de sexto grado de primaria, donde destac\u00f3 que el texto es el primero de una nueva generaci\u00f3n de libros. En este sentido, se\u00f1al\u00f3 que el ejemplar cuenta [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150],"tags":[4327,887,1210,395,153,157],"yst_prominent_words":[7652,8579,10553,8571,8564,8561,8666,8568,7536,9742],"class_list":["post-93802","post","type-post","status-publish","format-standard","hentry","category-metropoli-tlaxcala","tag-florentino-dominguez-ordonez","tag-libros","tag-primaria","tag-sepe","tag-tlaxcala","tag-tlaxslide"],"_links":{"self":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/93802"}],"collection":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/comments?post=93802"}],"version-history":[{"count":0,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/posts\/93802\/revisions"}],"wp:attachment":[{"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/media?parent=93802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/categories?post=93802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/tags?post=93802"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/sintesis.com.mx\/tlaxcala\/wp-json\/wp\/v2\/yst_prominent_words?post=93802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}